{"id":12506,"date":"2023-04-18T11:29:04","date_gmt":"2023-04-18T15:29:04","guid":{"rendered":"https:\/\/intosai.nclud.com\/?post_type=journal-entry&#038;p=12506"},"modified":"2023-04-28T02:34:27","modified_gmt":"2023-04-28T06:34:27","slug":"donner-une-voix-mondiale-a-lintosai-par-la-communication-et-la-collaboration","status":"publish","type":"journal-entry","link":"https:\/\/intosaijournal.org\/fr\/journal-entry\/donner-une-voix-mondiale-a-lintosai-par-la-communication-et-la-collaboration\/","title":{"rendered":"Donner une voix mondiale \u00e0 l&#8217;INTOSAI par la communication et la collaboration"},"content":{"rendered":"\n<p>Les Institutions sup\u00e9rieures de contr\u00f4le des finances publiques (ISC) auditent de mani\u00e8re ind\u00e9pendante et objective leurs gouvernements afin de s&#8217;assurer que l&#8217;utilisation des fonds publics profite aux citoyennes et citoyens. Alors que les d\u00e9fis auxquels le monde fait face deviennent plus complexes, les ISC peuvent utiliser et amplifier leur voix aux niveaux individuel, r\u00e9gional et mondial afin de d\u00e9montrer leur impact et de garantir la reddition de comptes.\u00a0<\/p>\n\n\n\n<p>Le document du Th\u00e8me II : \u00ab&nbsp;Une voix globale, un r\u00e9sultat global, un impact de grande port\u00e9e&nbsp;\u00bb, compare l&#8217;audit et la reddition de comptes entre les ISC. Il identifie l&#8217;ind\u00e9pendance, le professionnalisme, comme \u00e9tant importants pour insuffler la confiance dans les ISC, et am\u00e9liorer la gestion des finances publiques et de l&#8217;administration.<\/p>\n\n\n\n<p>Le document identifie les points communs des ISC et partage certaines des diff\u00e9rences, telles que les capacit\u00e9s de communication et de technologie.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Le pr\u00e9sident entrant du Comit\u00e9 directeur de l&#8217;INTOSAI, M. Dantas, partage l&#8217;importance de la communication et de la collaboration pour la voix mondiale de l&#8217;INTOSAI<\/strong><\/strong><\/h2>\n\n\n\n<p>M. le Ministre Bruno Dantas, Pr\u00e9sident de la TCU et pr\u00e9sident entrant du Comit\u00e9 directeur de l&#8217;INTOSAI, a d\u00e9clar\u00e9 que la voix mondiale de l&#8217;INTOSAI communique ses valeurs et son impact.\u00a0 Pour exploiter plus efficacement cette voix, l&#8217;INTOSAI peut \u00e9largir et renforcer la communication. Il y a une grande valeur \u00e0 communiquer le travail des ISC autour de th\u00e8mes communs et tr\u00e8s pertinents. Il a fait \u00e9cho \u00e0 la devise de l&#8217;INTOSAI, les avantages de l&#8217;exp\u00e9rience mutuelle, et a d\u00e9clar\u00e9 que les ISC peuvent coop\u00e9rer pour encourager l&#8217;apprentissage et le d\u00e9veloppement vers le professionnalisme, l&#8217;ind\u00e9pendance et l&#8217;exhaustivit\u00e9 de l&#8217;analyse. Chaque ISC contribue au processus collaboratif d&#8217;apprentissage institutionnel au sein de son propre pays, avec d&#8217;autres ISC au sein des Organisations r\u00e9gionales de l&#8217;INTOSAI, et avec ses pairs dans le monde entier. Il a \u00e9galement d\u00e9clar\u00e9 : \u00ab\u00a0L&#8217;INTOSAI est aussi consciente depuis longtemps qu&#8217;en tant qu&#8217;institution multilat\u00e9rale, elle n&#8217;est pas seule dans le monde.\u00a0\u00bb L&#8217;INTOSAI reconna\u00eet les avantages de s&#8217;engager avec la communaut\u00e9 internationale, comme le montrent les partenariats avec la Coop\u00e9ration INTOSAI-bailleurs de fonds visant \u00e0 aider les ISC \u00e0 renforcer leurs capacit\u00e9s, et la collaboration avec les Nations Unies, la Banque mondiale et l&#8217;OCDE.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Les pan\u00e9listes discutent de la voix mondiale et de la coop\u00e9ration intergouvernementale de l&#8217;INTOSAI<\/strong><\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"541\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.23.40-PM-1024x541.png\" alt=\"\" class=\"wp-image-10903\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.23.40-PM-1024x541.png 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.23.40-PM-300x158.png 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.23.40-PM-768x406.png 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.23.40-PM-1536x811.png 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.23.40-PM-2048x1082.png 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.23.40-PM-1320x697.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>M. J\u00e1nos Bert\u00f3k, Directeur par int\u00e9rim de la Direction de la gouvernance publique de l&#8217;Organisation de coop\u00e9ration et de d\u00e9veloppement \u00e9conomiques (OCDE), a soulign\u00e9 le r\u00f4le de l&#8217;OCDE dans le dialogue entre les gouvernements, les ISC, les parties prenantes et la soci\u00e9t\u00e9 civile. L&#8217;OCDE dispose d&#8217;une alliance d&#8217;auditeurs, qui r\u00e9unit des perspectives de contr\u00f4le interne et des auditeurs externes pour discuter et d\u00e9velopper les aspects techniques professionnels de l&#8217;audit du secteur public. L&#8217;OCDE soutient une meilleure compr\u00e9hension, une meilleure pr\u00e9paration et une meilleure r\u00e9silience face aux futures situations de crise, o\u00f9 les ISC peuvent jouer un r\u00f4le cl\u00e9 en mati\u00e8re de reddition de comptes. Il a d\u00e9clar\u00e9 que l&#8217;OCDE se r\u00e9jouit de renforcer la collaboration avec les ISC et la communaut\u00e9 de l&#8217;INTOSAI, et de soutenir les ISC en tant que centre de connaissances pour les preuves par le biais de donn\u00e9es et d&#8217;analyses.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"807\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.24.37-PM-1024x807.png\" alt=\"\" class=\"wp-image-10908\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.24.37-PM-1024x807.png 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.24.37-PM-300x236.png 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.24.37-PM-768x605.png 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.24.37-PM-1536x1210.png 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.24.37-PM-1320x1040.png 1320w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.24.37-PM.png 2034w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>M. Bob Saum, Directeur des normes, des achats et de la gestion financi\u00e8re \u00e0 la Banque mondiale, a d\u00e9clar\u00e9 que la cr\u00e9dibilit\u00e9 et l&#8217;objectivit\u00e9 peuvent am\u00e9liorer la compr\u00e9hension et consolider la voix mondiale de l&#8217;INTOSAI. Les ISC peuvent reconna\u00eetre les questions les plus pertinentes au niveau national, identifier les points communs entre les r\u00e9gions, et consid\u00e9rer les th\u00e8mes les plus importants \u00e0 \u00e9lever au niveau mondial. Il a soulign\u00e9 l&#8217;importance des organes r\u00e9gionaux de l&#8217;INTOSAI et leur expertise pour bien vouloir informer le d\u00e9bat public. Ils peuvent \u00e9largir la compr\u00e9hension r\u00e9gionale et mondiale des moteurs et des r\u00e9ponses aux situations de fragilit\u00e9 et de crise. Malgr\u00e9 un acc\u00e8s accru aux plateformes num\u00e9riques et aux appareils mobiles, des millions de personnes n&#8217;ont pas voix au chapitre dans l&#8217;ar\u00e8ne publique. L&#8217;INTOSAI et les ISC membres peuvent servir de voix ind\u00e9pendante et objective pour ceux qui n&#8217;en ont pas. Il a d\u00e9clar\u00e9 que la Banque mondiale reste un partenaire ind\u00e9fectible de l&#8217;INTOSAI et des ISC du monde entier.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.06-PM-1024x529.png\" alt=\"\" class=\"wp-image-10913\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.06-PM-1024x529.png 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.06-PM-300x155.png 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.06-PM-768x397.png 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.06-PM-1536x794.png 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.06-PM-2048x1059.png 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.06-PM-1320x682.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>M. Einar G\u00f8rrissen, Directeur g\u00e9n\u00e9ral de l&#8217;Initiative de d\u00e9veloppement de l&#8217;INTOSAI (IDI), a pr\u00e9sent\u00e9 quatre r\u00e9flexions sur le renforcement de la voix de l&#8217;INTOSAI. Premi\u00e8rement, M. G\u00f8rrissen a d\u00e9clar\u00e9 que l&#8217;INTOSAI devrait renforcer la coordination et la communication au sein de la communaut\u00e9 de l&#8217;INTOSAI au niveau des ISC, ainsi qu&#8217;aux niveaux r\u00e9gional et mondial. Deuxi\u00e8mement, l&#8217;INTOSAI peut cr\u00e9er des objectifs communs. Comme l&#8217;INTOSAI est un \u00e9cosyst\u00e8me complexe compos\u00e9 de parties prenantes ayant des r\u00f4les vari\u00e9s et des responsabilit\u00e9s diverses, le fait d&#8217;avoir une vision et un objectif communs contribuera \u00e0 am\u00e9liorer le dialogue de travail en commun. Troisi\u00e8mement, l&#8217;INTOSAI doit \u00eatre proactive et avoir une approche inclusive des communaut\u00e9s des ISC et des autres parties prenantes. \u00c9couter les diff\u00e9rentes voix et exp\u00e9riences aide l&#8217;INTOSAI \u00e0 comprendre ceux qui risquent d&#8217;\u00eatre laiss\u00e9s pour compte. Enfin, l&#8217;INTOSAI doit apporter une valeur ajout\u00e9e gr\u00e2ce \u00e0 des audits de haute qualit\u00e9, r\u00e9actifs, opportuns et pertinents, afin d&#8217;am\u00e9liorer la conformit\u00e9 et la prestation des services publics. M. G\u00f8rrissen a d\u00e9clar\u00e9 que l&#8217;IDI croit fermement que des ISC efficaces, responsables et inclusives contribuent \u00e0 am\u00e9liorer les vies et les soci\u00e9t\u00e9s.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"557\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.27-PM-1024x557.png\" alt=\"\" class=\"wp-image-10918\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.27-PM-1024x557.png 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.27-PM-300x163.png 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.27-PM-768x418.png 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.27-PM-1536x836.png 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.27-PM-2048x1115.png 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/Screenshot-2023-01-04-at-2.25.27-PM-1320x718.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Le\u00e7ons tir\u00e9es et r\u00e9flexions des discussions en petits groupes dans les langues officielles de l&#8217;INTOSAI<\/strong><\/strong><\/h2>\n\n\n\n<p>Suite aux discussions en petits groupes, les discussions pl\u00e9ni\u00e8res du dernier jour ont port\u00e9 sur les le\u00e7ons tir\u00e9es et les r\u00e9flexions.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10948\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-1024x683.jpg\" alt=\"\" class=\"wp-image-10948\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-1024x683.jpg 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-300x200.jpg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-768x512.jpg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-1536x1024.jpg 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-2048x1365.jpg 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-660x440.jpg 660w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-1320x880.jpg 1320w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-193x128.jpg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-310x206.jpg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7469-467x310.jpg 467w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10928\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-1024x683.jpg\" alt=\"\" class=\"wp-image-10928\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-1024x683.jpg 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-300x200.jpg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-768x512.jpg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-1536x1024.jpg 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-2048x1365.jpg 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-660x440.jpg 660w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-1320x880.jpg 1320w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-193x128.jpg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-310x206.jpg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7451-467x310.jpg 467w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10943\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-1024x683.jpg\" alt=\"\" class=\"wp-image-10943\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-1024x683.jpg 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-300x200.jpg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-768x512.jpg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-1536x1024.jpg 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-2048x1365.jpg 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-660x440.jpg 660w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-1320x880.jpg 1320w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-193x128.jpg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-310x206.jpg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7435-467x310.jpg 467w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10953\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-1024x683.jpg\" alt=\"\" class=\"wp-image-10953\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-1024x683.jpg 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-300x200.jpg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-768x512.jpg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-1536x1024.jpg 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-2048x1365.jpg 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-660x440.jpg 660w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-1320x880.jpg 1320w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-193x128.jpg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-310x206.jpg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7419-467x310.jpg 467w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10923\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-1024x683.jpg\" alt=\"\" class=\"wp-image-10923\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-1024x683.jpg 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-300x200.jpg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-768x512.jpg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-1536x1024.jpg 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-2048x1365.jpg 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-660x440.jpg 660w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-1320x880.jpg 1320w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-193x128.jpg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-310x206.jpg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7417-467x310.jpg 467w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10933\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-1024x683.jpg\" alt=\"\" class=\"wp-image-10933\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-1024x683.jpg 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-300x200.jpg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-768x512.jpg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-1536x1024.jpg 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-2048x1365.jpg 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-660x440.jpg 660w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-1320x880.jpg 1320w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-193x128.jpg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-310x206.jpg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7410-467x310.jpg 467w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10958\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-1024x683.jpg\" alt=\"\" class=\"wp-image-10958\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-1024x683.jpg 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-300x200.jpg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-768x512.jpg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-1536x1024.jpg 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-2048x1365.jpg 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-660x440.jpg 660w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-1320x880.jpg 1320w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-193x128.jpg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-310x206.jpg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7372-467x310.jpg 467w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"10938\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-1024x683.jpg\" alt=\"\" class=\"wp-image-10938\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-1024x683.jpg 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-300x200.jpg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-768x512.jpg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-1536x1024.jpg 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-2048x1365.jpg 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-660x440.jpg 660w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-1320x880.jpg 1320w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-193x128.jpg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-310x206.jpg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-467x310.jpg 467w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><em><em>Ind\u00e9pendance des ISC<\/em><\/em><\/h3>\n\n\n\n<p>Les ISC ont convenu \u00e0 l&#8217;unanimit\u00e9 que l&#8217;ind\u00e9pendance des ISC \u00e9tait l&#8217;un des aspects les plus importants pour renforcer la voix mondiale de l&#8217;INTOSAI. Les ISC doivent inscrire leur ind\u00e9pendance dans la loi et disposer d&#8217;une autonomie financi\u00e8re pour g\u00e9rer leur budget. Le renforcement et la promotion de l&#8217;ind\u00e9pendance facilitent la capacit\u00e9 des ISC \u00e0 r\u00e9aliser des audits, \u00e0 publier et \u00e0 diffuser des rapports d&#8217;audit, et \u00e0 assurer le suivi des recommandations. En renfor\u00e7ant l&#8217;ind\u00e9pendance des ISC, celles-ci peuvent atteindre leurs objectifs de mani\u00e8re cr\u00e9dible, et am\u00e9liorer la transparence afin de gagner la confiance du public et des citoyens qu&#8217;elles servent. L&#8217;INTOSAI continue \u00e0 soutenir les ISC afin d&#8217;accro\u00eetre et de maintenir leur ind\u00e9pendance.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em><em>Strat\u00e9gies de communication externe<\/em><\/em><\/h3>\n\n\n\n<p>Les ISC s&#8217;accordent \u00e0 dire qu&#8217;il est n\u00e9cessaire d&#8217;am\u00e9liorer les strat\u00e9gies de communication externe afin d&#8217;aider les citoyens \u00e0 prendre conscience du r\u00f4le de l&#8217;ISC en mati\u00e8re de reddition de comptes publics et de l&#8217;impact de son travail. De nombreuses ISC ont \u00e9t\u00e9 confront\u00e9es \u00e0 des d\u00e9fis similaires, \u00e0 savoir que le public connaissait peu les ISC, leurs objectifs et leurs rapports. Les ISC ont convenu que le fait d&#8217;avoir des strat\u00e9gies coordonn\u00e9es de communication externe strat\u00e9gique aiderait \u00e0 faire conna\u00eetre les rapports d&#8217;audit des ISC \u00e0 un public plus large, et unifierait le message et la voix de l&#8217;INTOSAI.&nbsp;<\/p>\n\n\n\n<p>Les ISC sont au service des citoyens, et la communication ainsi que le plaidoyer sont une partie essentielle du travail d&#8217;audit des ISC. Bien que les ISC individuelles puissent varier en termes de format organisationnel et de responsabilit\u00e9s, il est important de communiquer au public que les ISC mettent en \u0153uvre des audits pour lutter contre la corruption, et promouvoir la transparence et la reddition de comptes. En soulignant l&#8217;importance de la voix mondiale de l&#8217;INTOSAI, les ISC et l&#8217;INTOSAI doivent tenir compte du fait que le destinataire du travail des ISC est souvent une partie prenante ou un citoyen au niveau national. Cependant, il est possible d&#8217;agr\u00e9ger les r\u00e9sultats d&#8217;audit nationaux pour parler d&#8217;une seule voix mondiale.<\/p>\n\n\n\n<p>Les ISC et l&#8217;INTOSAI devraient comprendre les besoins de leur public et la meilleure fa\u00e7on de communiquer avec lui. Les m\u00e9thodes traditionnelles de communication ont chang\u00e9, et les ISC devraient comprendre les besoins de communication d&#8217;aujourd&#8217;hui. Cibler et ajuster la communication permettrait aux ISC d&#8217;atteindre leur public et de l&#8217;aider \u00e0 comprendre le r\u00f4le et l&#8217;impact de l&#8217;ISC. Les ISC et l&#8217;INTOSAI devraient \u00e9galement mener des actions de sensibilisation aupr\u00e8s des m\u00e9dias et de la soci\u00e9t\u00e9 civile afin de mieux atteindre les citoyens.<\/p>\n\n\n\n<p>L&#8217;INTOSAI a cr\u00e9\u00e9 une Task force Communication, avec l&#8217;ISC du Br\u00e9sil et le Secr\u00e9tariat g\u00e9n\u00e9ral de l&#8217;INTOSAI comme pr\u00e9sidents, travaillant au sein de la Commission des affaires politiques, financi\u00e8res et administratives. La Task force \u00e9laborera des m\u00e9thodes pour utiliser la communication comme un outil strat\u00e9gique pour l&#8217;INTOSAI, et renforcera la voix mondiale de l&#8217;INTOSAI en tant qu&#8217;autorit\u00e9 en mati\u00e8re d&#8217;audit public et d&#8217;audit externe. La Task force s&#8217;est r\u00e9unie \u00e0 l&#8217;INCOSAI pour lancer les discussions et continuera \u00e0 travailler tout au long de 2023 pour coordonner et am\u00e9liorer la communication interne et externe de l&#8217;INTOSAI.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em><em>Partenariats entre organisations intergouvernementales<\/em><\/em><\/h3>\n\n\n\n<p>L&#8217;INTOSAI devrait poursuivre et renforcer les partenariats avec les organisations intergouvernementales afin de contribuer \u00e0 l&#8217;objectif de d\u00e9veloppement durable n\u00b0 16, qui consiste \u00e0 mettre en place des institutions efficaces, responsables et inclusives. La coop\u00e9ration avec des organisations telles que la Banque mondiale, le Fonds mon\u00e9taire international et les Nations Unies, par exemple, peut contribuer \u00e0 renforcer le r\u00f4le des normes d&#8217;audit internationales dans l&#8217;audit du secteur public. Les ISC ont convenu que les Organisations r\u00e9gionales de l&#8217;INTOSAI seraient de solides repr\u00e9sentants pour les partenariats avec ces organisations intergouvernementales au nom des ISC de la r\u00e9gion.&nbsp;<\/p>\n\n\n\n<p>Le Guide pratique sur le \u00ab Renforcement de la collaboration entre les Institutions sup\u00e9rieures de contr\u00f4le des finances publiques et les organismes charg\u00e9s de la lutte contre la corruption dans la pr\u00e9vention et la lutte contre la corruption&nbsp;\u00bb, une collaboration entre l&#8217;INTOSAI et l&#8217;Office des Nations Unies contre la drogue et le crime, dirig\u00e9e par l&#8217;ISC des \u00c9mirats arabes unis, constitue un exemple cl\u00e9 en mati\u00e8re de travail en commun. Le Guide fournit des conseils pratiques sur l&#8217;\u00e9tablissement et l&#8217;am\u00e9lioration des relations de travail entre les autorit\u00e9s au niveau national et aux niveaux r\u00e9gional et mondial. Par ailleurs, il fournit des exemples de bonnes pratiques en mati\u00e8re de pr\u00e9vention, d&#8217;application de la loi, d&#8217;enqu\u00eate et de recouvrement des avoirs, de coop\u00e9ration internationale, de renforcement des connaissances et des capacit\u00e9s, et d&#8217;utilisation des technologies de l&#8217;information et de la communication.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Partage des connaissances, renforcement des capacit\u00e9s et culture num\u00e9rique<\/em><\/h3>\n\n\n\n<p>En vue de renforcer la voix et l&#8217;impact de l&#8217;INTOSAI et des ISC au niveau mondial, les ISC doivent renforcer leurs capacit\u00e9s et partager leurs connaissances au sein de la communaut\u00e9 de l&#8217;INTOSAI. Les ISC ont not\u00e9 que les audits coop\u00e9ratifs identifient les priorit\u00e9s politiques cl\u00e9s dans le contexte de chaque ISC, et d\u00e9finissent des strat\u00e9gies et des th\u00e8mes pertinents dans les contextes r\u00e9gionaux et nationaux pour servir les int\u00e9r\u00eats des citoyens. L&#8217;\u00e9change des meilleures pratiques par le biais des audits coop\u00e9ratifs et du partage des connaissances rassemble les voix de nombreuses ISC en une seule voix mondiale de l&#8217;INTOSAI.&nbsp;<\/p>\n\n\n\n<p>Les ISC ont besoin de personnel qualifi\u00e9, de donn\u00e9es de haute qualit\u00e9 et d\u2019une culture num\u00e9rique pour r\u00e9aliser leur travail d&#8217;audit. Afin de mieux atteindre les citoyens et la soci\u00e9t\u00e9 civile et de partager les r\u00e9sultats et l&#8217;impact des rapports des ISC, ces derni\u00e8res devront renforcer leur capacit\u00e9 \u00e0 utiliser les technologies modernes et les m\u00e9dias sociaux. La communaut\u00e9 de l&#8217;INTOSAI au niveau mondial et r\u00e9gional peut coop\u00e9rer pour professionnaliser les ISC. La culture num\u00e9rique et les formations techniques pourraient aider les ISC \u00e0 partager leurs \u00e9nonc\u00e9s de mission, leurs plans strat\u00e9giques et leurs rapports via l&#8217;Internet et les m\u00e9dias sociaux. En d\u00e9veloppant la culture num\u00e9rique des ISC, les citoyens pourront acc\u00e9der aux rapports et comprendre le r\u00f4le important des ISC dans la promotion de la reddition de comptes.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-scaled.jpg\" alt=\"\" class=\"wp-image-10968\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-scaled.jpg 2560w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-300x200.jpg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-1024x683.jpg 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-768x512.jpg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-1536x1024.jpg 1536w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-2048x1365.jpg 2048w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-660x440.jpg 660w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-1320x880.jpg 1320w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-193x128.jpg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-310x206.jpg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_8443-edited-467x310.jpg 467w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p>L&#8217;engagement de l&#8217;INTOSAI envers l&#8217;audit public, la reddition de comptes et la transparence peut faciliter une voix unifi\u00e9e et mondiale. Les ISC ont reconnu qu&#8217;elles doivent assurer leur ind\u00e9pendance, communiquer efficacement, entretenir des partenariats avec des organisations internationales et d\u00e9velopper des capacit\u00e9s techniques. Une voix mondiale plus forte de l&#8217;INTOSAI permettra de communiquer plus efficacement les r\u00e9sultats consolid\u00e9s du travail effectu\u00e9 par les ISC afin de sensibiliser le public \u00e0 l&#8217;impact et \u00e0 la valeur de l&#8217;INTOSAI et des ISC. Comme l&#8217;a d\u00e9clar\u00e9 l&#8217;Auditeur g\u00e9n\u00e9ral Sami Ylaoutinen du Bureau national d&#8217;audit de Finlande, \u00ab\u00a0La voix mondiale est une question de travail conjoint, de partage des exp\u00e9riences de coop\u00e9ration et d&#8217;am\u00e9lioration de l&#8217;impact des ISC&#8230; Les ISC ont des messages et des r\u00e9sultats pr\u00e9cieux \u00e0 partager\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Institutions sup\u00e9rieures de contr\u00f4le des finances publiques (ISC) auditent de mani\u00e8re ind\u00e9pendante et objective&#8230;<\/p>\n","protected":false},"author":5,"featured_media":10940,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[2623],"content-tags":[1762,919,1763,2624,3825,1876,2759,1820,2758,1781],"country":[],"region":[],"section":[2641],"coauthors":[],"class_list":["post-12506","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-incosai-xxiv","content-tags-collaboration-fr","content-tags-communication-fr","content-tags-cooperation-fr","content-tags-incosai","content-tags-incosai-fr","content-tags-incosai2022-fr","content-tags-independance","content-tags-lindependance","content-tags-le-partage-des-connaissances","content-tags-partage-des-connaissances","section-navigating_the_journey-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Donner une voix mondiale \u00e0 l&#039;INTOSAI par la communication et la collaboration - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donner une voix mondiale \u00e0 l&#039;INTOSAI par la communication et la collaboration - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"Les Institutions sup\u00e9rieures de contr\u00f4le des finances publiques (ISC) auditent de mani\u00e8re ind\u00e9pendante et objective...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-28T06:34:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Jessica Du\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/\",\"url\":\"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/\",\"name\":\"Donner une voix mondiale \u00e0 l'INTOSAI par la communication et la collaboration - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/intosaijournal.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-scaled.jpg\",\"datePublished\":\"2023-04-18T15:29:04+00:00\",\"dateModified\":\"2023-04-28T06:34:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/#primaryimage\",\"url\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-scaled.jpg\",\"contentUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"INCOSAI Theme 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donner une voix mondiale \u00e0 l&#8217;INTOSAI par la communication et la collaboration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intosaijournal.org\/#website\",\"url\":\"https:\/\/intosaijournal.org\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intosaijournal.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intosaijournal.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intosaijournal.org\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/intosaijournal.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Donner une voix mondiale \u00e0 l'INTOSAI par la communication et la collaboration - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/","og_locale":"fr_FR","og_type":"article","og_title":"Donner une voix mondiale \u00e0 l'INTOSAI par la communication et la collaboration - INTOSAI Journal","og_description":"Les Institutions sup\u00e9rieures de contr\u00f4le des finances publiques (ISC) auditent de mani\u00e8re ind\u00e9pendante et objective...","og_url":"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/","og_site_name":"INTOSAI Journal","article_modified_time":"2023-04-28T06:34:27+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"12 minutes","Written by":"Jessica Du"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/","url":"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/","name":"Donner une voix mondiale \u00e0 l'INTOSAI par la communication et la collaboration - INTOSAI Journal","isPartOf":{"@id":"https:\/\/intosaijournal.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/#primaryimage"},"image":{"@id":"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/#primaryimage"},"thumbnailUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-scaled.jpg","datePublished":"2023-04-18T15:29:04+00:00","dateModified":"2023-04-28T06:34:27+00:00","breadcrumb":{"@id":"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/#primaryimage","url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-scaled.jpg","contentUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/04\/DSC_7370-scaled.jpg","width":2560,"height":1707,"caption":"INCOSAI Theme 2"},{"@type":"BreadcrumbList","@id":"https:\/\/intosaijournal.org\/journal-entry\/developing-a-global-voice-for-intosai-through-communication-and-collaboration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Donner une voix mondiale \u00e0 l&#8217;INTOSAI par la communication et la collaboration"}]},{"@type":"WebSite","@id":"https:\/\/intosaijournal.org\/#website","url":"https:\/\/intosaijournal.org\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/intosaijournal.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intosaijournal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/intosaijournal.org\/#organization","name":"INTOSAI Journal","url":"https:\/\/intosaijournal.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/journal-entry\/12506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":2,"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/journal-entry\/12506\/revisions"}],"predecessor-version":[{"id":12508,"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/journal-entry\/12506\/revisions\/12508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/media\/10940"}],"wp:attachment":[{"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/media?parent=12506"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/journal-categories?post=12506"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/content-tags?post=12506"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/country?post=12506"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/region?post=12506"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/section?post=12506"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/intosaijournal.org\/fr\/wp-json\/wp\/v2\/coauthors?post=12506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}