{"id":40269,"date":"2026-04-21T18:28:37","date_gmt":"2026-04-21T22:28:37","guid":{"rendered":"https:\/\/intosaijournal.org\/team\/kimberly-bassett-nelson\/"},"modified":"2026-04-21T18:32:50","modified_gmt":"2026-04-21T22:32:50","slug":"kimberly-bassett-nelson","status":"publish","type":"team","link":"https:\/\/intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/","title":{"rendered":"Kimberly Bassett-Nelson"},"content":{"rendered":"\n<p><strong>Kimberly (Kim) Bassett-Nelson<\/strong> trabaja como Interventora en la Oficina de Rendici\u00f3n de Cuentas del Gobierno de EE.UU., dentro de Gesti\u00f3n Financiera y Operaciones Empresariales (FMBO), donde dirige la supervisi\u00f3n de las operaciones de Gesti\u00f3n de Adquisiciones, Presupuesto, Gesti\u00f3n Financiera, Controles Internos y Viajes. Contable experimentada y profesional del presupuesto, es conocida por ofrecer una visi\u00f3n financiera estrat\u00e9gica, reforzar la administraci\u00f3n fiscal y garantizar el cumplimiento de los requisitos federales. <\/p>\n\n<p>Con m\u00e1s de 34 a\u00f1os de experiencia en presupuestaci\u00f3n, contabilidad y auditor\u00eda federales, Kim ha desempe\u00f1ado altos cargos directivos en todo el gobierno. Ha sido Jefa de la Subdivisi\u00f3n de Ejecuci\u00f3n Presupuestaria de la Administraci\u00f3n Nacional de la Aeron\u00e1utica y del Espacio y Directora Presupuestaria de la Comisi\u00f3n Federal de Comunicaciones. Su carrera incluye tambi\u00e9n puestos clave en el Departamento de Trabajo, la Administraci\u00f3n Federal de Aviaci\u00f3n, la Comisi\u00f3n Reguladora Nuclear y el Departamento de Energ\u00eda, lo que le da una perspectiva global de todo el ciclo financiero federal, desde la formulaci\u00f3n y ejecuci\u00f3n hasta la gesti\u00f3n del rendimiento.  <\/p>\n\n<p>M\u00e1s all\u00e1 de sus conocimientos t\u00e9cnicos, Kim es muy respetada por su liderazgo y su compromiso con las personas. Da prioridad a la tutor\u00eda y el desarrollo del personal, impulsando mejoras de los procesos que reduzcan la carga administrativa y abogando por recursos que mejoren tanto la eficacia organizativa como el bienestar de los empleados. <\/p>\n\n<p>Kim tiene un m\u00e1ster en Gesti\u00f3n Empresarial por la Universidad de Maryland y una licenciatura en Econom\u00eda por la Universidad Estatal de Bowie.<\/p>\n","protected":false},"featured_media":40274,"template":"","class_list":["post-40269","team","type-team","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kimberly Bassett-Nelson - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kimberly Bassett-Nelson - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"Kimberly (Kim) Bassett-Nelson trabaja como Interventora en la Oficina de Rendici\u00f3n de Cuentas del Gobierno...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T22:32:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/04\/Board-Bios-K.Bassett-Nelson.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Jessica Du\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/\",\"name\":\"Kimberly Bassett-Nelson - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/04\/Board-Bios-K.Bassett-Nelson.png\",\"datePublished\":\"2026-04-21T22:28:37+00:00\",\"dateModified\":\"2026-04-21T22:32:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/#primaryimage\",\"url\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/04\/Board-Bios-K.Bassett-Nelson.png\",\"contentUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/04\/Board-Bios-K.Bassett-Nelson.png\",\"width\":1040,\"height\":880},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kimberly Bassett-Nelson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#website\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intosaijournal.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kimberly Bassett-Nelson - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/","og_locale":"es_ES","og_type":"article","og_title":"Kimberly Bassett-Nelson - INTOSAI Journal","og_description":"Kimberly (Kim) Bassett-Nelson trabaja como Interventora en la Oficina de Rendici\u00f3n de Cuentas del Gobierno...","og_url":"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/","og_site_name":"INTOSAI Journal","article_modified_time":"2026-04-21T22:32:50+00:00","og_image":[{"width":1040,"height":880,"url":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/04\/Board-Bios-K.Bassett-Nelson.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"1 minute","Written by":"Jessica Du"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/","url":"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/","name":"Kimberly Bassett-Nelson - INTOSAI Journal","isPartOf":{"@id":"https:\/\/www.intosaijournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/#primaryimage"},"image":{"@id":"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/#primaryimage"},"thumbnailUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/04\/Board-Bios-K.Bassett-Nelson.png","datePublished":"2026-04-21T22:28:37+00:00","dateModified":"2026-04-21T22:32:50+00:00","breadcrumb":{"@id":"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/#primaryimage","url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/04\/Board-Bios-K.Bassett-Nelson.png","contentUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/04\/Board-Bios-K.Bassett-Nelson.png","width":1040,"height":880},{"@type":"BreadcrumbList","@id":"https:\/\/www.intosaijournal.org\/es\/team\/kimberly-bassett-nelson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/es\/"},{"@type":"ListItem","position":2,"name":"Kimberly Bassett-Nelson"}]},{"@type":"WebSite","@id":"https:\/\/www.intosaijournal.org\/es\/#website","url":"https:\/\/www.intosaijournal.org\/es\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/www.intosaijournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intosaijournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.intosaijournal.org\/es\/#organization","name":"INTOSAI Journal","url":"https:\/\/www.intosaijournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/team\/40269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/team"}],"about":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/types\/team"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/media\/40274"}],"wp:attachment":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/media?parent=40269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}