{"id":42185,"date":"2026-06-30T13:00:00","date_gmt":"2026-06-30T17:00:00","guid":{"rendered":"https:\/\/intosaijournal.org\/?post_type=journal-entry&#038;p=42185"},"modified":"2026-07-14T18:10:39","modified_gmt":"2026-07-14T22:10:39","slug":"tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje","status":"publish","type":"journal-entry","link":"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/","title":{"rendered":"\u00abTocando el futuro\u00bb: la historia de IDI sobre c\u00f3mo ha formado a generaciones de especialistas en formaci\u00f3n y aprendizaje"},"content":{"rendered":"\n<p>Autora: Archana Shirsat, subdirectora general de la Iniciativa de Desarrollo de la INTOSAI (IDI)<\/p>\n\n\n\n<p><strong><em>\u00abToco el futuro. Ense\u00f1o.\u00bb \u2014 <\/em><\/strong>dijo Christa McAuliffe, una profesora seleccionada para el programa \u00abTeacher in Space\u00bb de la NASA en 1986, destacando el profundo impacto que tienen los educadores a la hora de formar a las futuras generaciones, a los innovadores y a los l\u00edderes. Su lema refleja la idea de que la ense\u00f1anza es algo que dura toda la vida, que tiene una gran influencia y que, a menudo, da forma al futuro.<\/p>\n\n\n\n<p>No te sorprender\u00e1, pues, que ahora que me siento a escribir mis reflexiones y experiencias m\u00e1s queridas sobre mi crecimiento junto a la Iniciativa de Desarrollo de la INTOSAI (IDI), la historia m\u00e1s emblem\u00e1tica que me viene a la mente sea la del camino recorrido por la IDI para formar a su personal: equipos de especialistas en formaci\u00f3n, especialistas en e-learning, especialistas en aprendizaje mixto y facilitadores.  <\/p>\n\n\n\n<p>Es una historia que abarca los a\u00f1os de IDI en Canad\u00e1 y Noruega; una historia que ha marcado la vida de cientos de personas y de muchas Instituciones Superiores de Auditor\u00eda (ISA) en todas las regiones de la INTOSAI. Es una historia que ha resistido el paso del tiempo, sabi\u00e9ndose adaptar a las necesidades cambiantes; pasando de formar a personas a fortalecer instituciones para lograr sostenibilidad e impacto. \u00a1Tambi\u00e9n es mi historia!  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>C\u00f3mo convertirte en especialista en formaci\u00f3n certificado por el IDI  <\/strong><\/h2>\n\n\n\n<p>Conoc\u00ed el enfoque sistem\u00e1tico de formaci\u00f3n del IDI a principios de la d\u00e9cada de 2000, mientras aprend\u00eda a realizar una auditor\u00eda financiera en la Academia Nacional de Auditor\u00eda y Contabilidad de Shimla. En 2002, la EFS de la India me seleccion\u00f3 para participar en el programa del IDI-ASOSAI destinado a formar a la segunda promoci\u00f3n de especialistas en formaci\u00f3n para la ASOSAI. Lo que vino despu\u00e9s fueron siete semanas de una experiencia que me cambi\u00f3 la vida. Fue fascinante interactuar y aprender con m\u00e1s de 30 participantes de las EFS de toda la regi\u00f3n de la ASOSAI. Fue la primera vez que vi tanta diversidad de EFS, idiomas, culturas y pr\u00e1cticas de auditor\u00eda. Un equipo de facilitadores de la primera promoci\u00f3n de especialistas en formaci\u00f3n de la ASOSAI nos gui\u00f3 en nuestro proceso de aprendizaje sobre los principios y la teor\u00eda de la formaci\u00f3n de adultos, el an\u00e1lisis de las necesidades formativas, el dise\u00f1o y desarrollo de cursos, y las habilidades de facilitaci\u00f3n. Aprendimos haciendo: practicando y aplicando nuestros conocimientos y habilidades. Lo que m\u00e1s me inspir\u00f3 no fueron solo las competencias t\u00e9cnicas, sino los valores y las cualidades personales que demostraron mis profesores.         <\/p>\n\n\n\n<p>Demostraron confianza en nuestra capacidad y experiencia, crearon un espacio seguro para que pudi\u00e9ramos aprender, escucharon nuestras ideas y emociones, y nos plantearon preguntas que nos hac\u00edan reflexionar. Siempre pod\u00edamos confiar en que nos dar\u00edan comentarios reveladores, y tuvimos la oportunidad de poner en pr\u00e1ctica lo aprendido dise\u00f1ando una formaci\u00f3n sobre auditor\u00edas. Al cabo de siete semanas, me certifiqu\u00e9 como especialista en formaci\u00f3n de IDI, pas\u00e9 a formar parte de una comunidad regional y global de especialistas en formaci\u00f3n, \u00a1y eso me cambi\u00f3 la vida! Cuento esta historia porque no es solo la m\u00eda, sino la de la mayor\u00eda de los especialistas en formaci\u00f3n certificados por IDI.   <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Formar a las nuevas generaciones de especialistas en formaci\u00f3n<\/strong> <\/h2>\n\n\n\n<p>Entre 1998 y 2015, el IDI cre\u00f3 una comunidad de especialistas en formaci\u00f3n en \u00e1rabe, ingl\u00e9s, franc\u00e9s, espa\u00f1ol y ruso en todas las regiones de la INTOSAI. Estos grupos se encargaron de dise\u00f1ar, desarrollar e impartir iniciativas de formaci\u00f3n y aprendizaje en sus propias EFS, para sus regiones y para el IDI. Devolvieron lo que hab\u00edan recibido contribuyendo a la formaci\u00f3n de nuevas promociones de especialistas en formaci\u00f3n y crecieron como l\u00edderes de las EFS; algunos llegaron a ser presidentes de las EFS y miembros de la alta direcci\u00f3n de las mismas. \u00a1Algunos de nosotros tambi\u00e9n nos unimos a la IDI!     <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-IDIs-Journey-of-Growing-Training-Timeline4-1024x614.png\" alt=\"\" class=\"wp-image-42226\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-IDIs-Journey-of-Growing-Training-Timeline4-1024x614.png 1024w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-IDIs-Journey-of-Growing-Training-Timeline4-300x180.png 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-IDIs-Journey-of-Growing-Training-Timeline4-768x461.png 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-IDIs-Journey-of-Growing-Training-Timeline4.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Fuente: Iniciativa de Desarrollo de la INTOSAI<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Adaptarse a los nuevos tiempos: apostar por la digitalizaci\u00f3n en el aprendizaje  <\/strong><\/h2>\n\n\n\n<p>Para adaptarnos a los nuevos tiempos, IDI empez\u00f3 a experimentar con el e-learning y pas\u00f3 de la formaci\u00f3n aislada a iniciativas de desarrollo de capacidades. Transformamos el formato de formaci\u00f3n presencial especializada en una combinaci\u00f3n de formatos presenciales y en l\u00ednea para formar a la pr\u00f3xima generaci\u00f3n de especialistas en e-learning, especialistas en aprendizaje mixto y administradores de sistemas de gesti\u00f3n del aprendizaje (LMS). En 2015, lanzamos el propio LMS de IDI. Para 2019, hab\u00edamos formado a 136 administradores de LMS y a 104 especialistas certificados en aprendizaje electr\u00f3nico en todas las regiones de la INTOSAI, adem\u00e1s de 32 especialistas certificados en aprendizaje mixto en la ASOSAI. A lo largo de los a\u00f1os, hemos ayudado tanto a las regiones como a las EFS a desarrollar y gestionar los LMS. Tambi\u00e9n hemos escrito un libro de texto para especialistas en e-learning: <a href=\"https:\/\/idi.no\/initiative-search\/?_initiative=digital-education-infrastructure\">\u00abInitiative Preselect &#8211; IDI<\/a>\u00bb.     <\/p>\n\n\n\n<p>Aunque los formatos, las plataformas y la forma de impartir la formaci\u00f3n han cambiado, la esencia de la filosof\u00eda y los valores formativos de IDI se ha mantenido igual. El enfoque centrado en el alumno y facilitador, que potencia el empoderamiento de las mujeres, la inclusi\u00f3n y el respeto por la diversidad y el contexto de cada pa\u00eds, se ha mantenido intacto.   <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Resiliencia en tiempos de la COVID: interacciones saludables en l\u00ednea  <\/strong><\/h2>\n\n\n\n<p>Ha sido precisamente esta inversi\u00f3n en personas e infraestructuras para la educaci\u00f3n digital lo que nos ha ayudado a mantenernos fuertes durante la pandemia de COVID. \u00a1Ha sido muy alentador ver c\u00f3mo el personal de IDI y nuestro equipo de expertos se han adaptado con tanto entusiasmo al desarrollo de capacidades y a las interacciones en l\u00ednea! A ra\u00edz de esta experiencia, hemos escrito \u00abInteracciones saludables\u00bb, donde recopilamos nuestras experiencias y recomendaciones para interactuar en l\u00ednea.    <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>De las personas a las instituciones: un enfoque facilitador para el desarrollo de capacidades  <\/strong><\/h2>\n\n\n\n<p>Desde 2005, IDI empez\u00f3 a pasar de la formaci\u00f3n aislada a un apoyo m\u00e1s integral para las personas, los procesos y las instituciones. Independientemente del tema o la naturaleza de nuestro apoyo, son las habilidades de facilitaci\u00f3n y el enfoque los que han llevado al empoderamiento y al cambio sostenible. Al reconocer el poder del enfoque de facilitaci\u00f3n, lo hemos integrado en la mayor\u00eda de nuestros crecientes grupos de recursos. Empezamos a experimentar con la creaci\u00f3n de grupos de facilitadores de las ISSAI: personas con un profundo conocimiento de la implementaci\u00f3n de las ISSAI y habilidades de facilitaci\u00f3n. Tambi\u00e9n incluimos un aprendizaje r\u00e1pido en habilidades de dise\u00f1o y facilitaci\u00f3n como parte de la formaci\u00f3n de mentores para todos los expertos de IDI.      <\/p>\n\n\n\n<p>Nuestro equipo de especialistas en formaci\u00f3n y e-learning ha desempe\u00f1ado un papel clave, con importantes aportaciones en especie al dise\u00f1o, desarrollo y puesta en marcha de iniciativas clave como la certificaci\u00f3n PESA para auditores, el programa \u00abJ\u00f3venes L\u00edderes de las EFS\u00bb y las pr\u00e1cticas de auditor\u00eda sostenible. Y lo que es m\u00e1s importante, el enfoque facilitador de IDI gu\u00eda todo nuestro dise\u00f1o de desarrollo de capacidades: empoderamos y facilitamos, en lugar de limitar a proporcionar. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Reinventar el aprendizaje y el crecimiento: formar a especialistas en desarrollo de competencias profesionales  <\/strong><\/h2>\n\n\n\n<p>A medida que seguimos impulsando los avances que marcan el futuro \u2014como la adopci\u00f3n de la norma ISSAI 150 sobre el desarrollo de las competencias de los auditores, la aparici\u00f3n de la tecnolog\u00eda y la IA y su naturaleza en constante evoluci\u00f3n, un orden mundial complejo e incierto, y la exigencia de no dejar a nadie atr\u00e1s\u2014, estamos replante\u00e1ndonos c\u00f3mo ser\u00e1 nuestra pr\u00f3xima generaci\u00f3n de especialistas en formaci\u00f3n. Para crear una generaci\u00f3n de especialistas en formaci\u00f3n preparada para el futuro, estamos dise\u00f1ando un \u00abCertificado Global para Especialistas en Desarrollo de Competencias Profesionales\u00bb.   <\/p>\n\n\n\n<p>Para terminar, con motivo del<sup>40.\u00ba<\/sup> aniversario de la IDI, me gustar\u00eda rendir homenaje a todos mis profesores y dar las gracias de todo coraz\u00f3n a las generaciones de especialistas en formaci\u00f3n y aprendizaje, a toda la gente de IDI, a todos nuestros socios tanto dentro como fuera de INTOSAI, y a todos nuestros expertos que han puesto todo su coraz\u00f3n y su alma en el desarrollo de las personas y las instituciones. Me gustar\u00eda despedirme con la promesa de seguir marcando el futuro formando a las pr\u00f3ximas generaciones de quienes, a su vez, formar\u00e1n a otros. \u00a1Que nuestra tribu siga creciendo!  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abToco el futuro. Ense\u00f1o\u00bb, dijo Christa McAuliffe, una profesora seleccionada para el programa \u00abTeacher in Space\u00bb de la NASA en 1986, destacando el profundo impacto que tienen los educadores a la hora de formar a las futuras generaciones, a los innovadores y a los l\u00edderes. Su lema refleja la filosof\u00eda de que la ense\u00f1anza es algo que dura toda la vida, tiene una gran influencia y, a menudo, da forma al futuro.<\/p>\n","protected":false},"author":12,"featured_media":42174,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[4503],"content-tags":[984,1019,1035,1036,1114,1194,1242],"country":[2939],"region":[],"section":[2633],"coauthors":[3281],"class_list":["post-42185","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-q2-2026","content-tags-capacity-development-es","content-tags-covid-19-es","content-tags-digital-transformation-es","content-tags-digitalization-es","content-tags-intosai-development-initiative-es","content-tags-resilience-es","content-tags-training-es","country-norway-5-es","section-special-contribution-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00abTocando el futuro\u00bb: la historia de IDI sobre c\u00f3mo ha formado a generaciones de especialistas en formaci\u00f3n y aprendizaje - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abTocando el futuro\u00bb: la historia de IDI sobre c\u00f3mo ha formado a generaciones de especialistas en formaci\u00f3n y aprendizaje - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"\u00abToco el futuro. Ense\u00f1o\u00bb, dijo Christa McAuliffe, una profesora seleccionada para el programa \u00abTeacher in Space\u00bb de la NASA en 1986, destacando el profundo impacto que tienen los educadores a la hora de formar a las futuras generaciones, a los innovadores y a los l\u00edderes. Su lema refleja la filosof\u00eda de que la ense\u00f1anza es algo que dura toda la vida, tiene una gran influencia y, a menudo, da forma al futuro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T22:10:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Archana-Shirsat.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Archana Shirsat\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/\",\"url\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/\",\"name\":\"\u00abTocando el futuro\u00bb: la historia de IDI sobre c\u00f3mo ha formado a generaciones de especialistas en formaci\u00f3n y aprendizaje - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Archana-Shirsat.png\",\"datePublished\":\"2026-06-30T17:00:00+00:00\",\"dateModified\":\"2026-07-14T22:10:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/#primaryimage\",\"url\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Archana-Shirsat.png\",\"contentUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Archana-Shirsat.png\",\"width\":1326,\"height\":880,\"caption\":\"Archana Shirsat. Fuente: Iniciativa de Desarrollo de la INTOSAI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abTocando el futuro\u00bb: la historia de IDI sobre c\u00f3mo ha formado a generaciones de especialistas en formaci\u00f3n y aprendizaje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#website\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intosaijournal.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abTocando el futuro\u00bb: la historia de IDI sobre c\u00f3mo ha formado a generaciones de especialistas en formaci\u00f3n y aprendizaje - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/","og_locale":"es_ES","og_type":"article","og_title":"\u00abTocando el futuro\u00bb: la historia de IDI sobre c\u00f3mo ha formado a generaciones de especialistas en formaci\u00f3n y aprendizaje - INTOSAI Journal","og_description":"\u00abToco el futuro. Ense\u00f1o\u00bb, dijo Christa McAuliffe, una profesora seleccionada para el programa \u00abTeacher in Space\u00bb de la NASA en 1986, destacando el profundo impacto que tienen los educadores a la hora de formar a las futuras generaciones, a los innovadores y a los l\u00edderes. Su lema refleja la filosof\u00eda de que la ense\u00f1anza es algo que dura toda la vida, tiene una gran influencia y, a menudo, da forma al futuro.","og_url":"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/","og_site_name":"INTOSAI Journal","article_modified_time":"2026-07-14T22:10:39+00:00","og_image":[{"width":1326,"height":880,"url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Archana-Shirsat.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"7 minutes","Written by":"Archana Shirsat"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/","url":"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/","name":"\u00abTocando el futuro\u00bb: la historia de IDI sobre c\u00f3mo ha formado a generaciones de especialistas en formaci\u00f3n y aprendizaje - INTOSAI Journal","isPartOf":{"@id":"https:\/\/www.intosaijournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/#primaryimage"},"image":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/#primaryimage"},"thumbnailUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Archana-Shirsat.png","datePublished":"2026-06-30T17:00:00+00:00","dateModified":"2026-07-14T22:10:39+00:00","breadcrumb":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/#primaryimage","url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Archana-Shirsat.png","contentUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Archana-Shirsat.png","width":1326,"height":880,"caption":"Archana Shirsat. Fuente: Iniciativa de Desarrollo de la INTOSAI"},{"@type":"BreadcrumbList","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/tocando-el-futuro-la-historia-de-idi-sobre-como-ha-formado-a-generaciones-de-especialistas-en-formacion-y-aprendizaje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abTocando el futuro\u00bb: la historia de IDI sobre c\u00f3mo ha formado a generaciones de especialistas en formaci\u00f3n y aprendizaje"}]},{"@type":"WebSite","@id":"https:\/\/www.intosaijournal.org\/es\/#website","url":"https:\/\/www.intosaijournal.org\/es\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/www.intosaijournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intosaijournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.intosaijournal.org\/es\/#organization","name":"INTOSAI Journal","url":"https:\/\/www.intosaijournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/42185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/users\/12"}],"version-history":[{"count":5,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/42185\/revisions"}],"predecessor-version":[{"id":42385,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/42185\/revisions\/42385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/media\/42174"}],"wp:attachment":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/media?parent=42185"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-categories?post=42185"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/content-tags?post=42185"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/country?post=42185"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/region?post=42185"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/section?post=42185"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/coauthors?post=42185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}