{"id":41639,"date":"2026-06-30T08:19:00","date_gmt":"2026-06-30T12:19:00","guid":{"rendered":"https:\/\/intosaijournal.org\/?post_type=journal-entry&#038;p=41639"},"modified":"2026-07-14T16:40:03","modified_gmt":"2026-07-14T20:40:03","slug":"auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico","status":"publish","type":"journal-entry","link":"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/","title":{"rendered":"Auditor\u00eda de la informaci\u00f3n financiera a revelar: mejores pr\u00e1cticas e impacto en los informes por segmentos del sector p\u00fablico"},"content":{"rendered":"\n<p>Autor: Autoridad Estatal de Rendici\u00f3n de Cuentas de la Rep\u00fablica \u00c1rabe de Egipto<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Introducci\u00f3n<\/h2>\n\n\n\n<p>La revelaci\u00f3n de los estados financieros se considera un aspecto importante para la mejora de la transparencia y la rendici\u00f3n de cuentas y, por tanto, para la lucha contra la corrupci\u00f3n. Las auditor\u00edas financieras que realizan las Entidades Fiscalizadoras Superiores (EFS) desempe\u00f1an un papel efectivo en la fiscalizaci\u00f3n de esta informaci\u00f3n revelada. En el presente art\u00edculo abordaremos la auditor\u00eda de la informaci\u00f3n a revelar en los informes por segmentos del sector p\u00fablico, presentando un estudio de caso sobre dicha informaci\u00f3n como elemento relevante a efectos de potenciar la transparencia y la rendici\u00f3n de cuentas.<\/p>\n\n\n\n<p>La Norma Internacional de Contabilidad del Sector P\u00fablico 18 (NICSP 18) establece los principios para la informaci\u00f3n financiera por segmentos en el sector p\u00fablico, constatando que la informaci\u00f3n por segmentos refuerza la transparencia en la informaci\u00f3n financiera y habilita a la entidad para cumplir sus obligaciones de rendici\u00f3n de cuentas (NICSP 18, b), sobre una base apropiada para la evaluaci\u00f3n del rendimiento y las decisiones de asignaci\u00f3n de recursos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Riesgos inherentes a la presentaci\u00f3n de informaci\u00f3n financiera por segmentos<\/h2>\n\n\n\n<p>La NICSP 18 adopta el enfoque de determinar el nivel de detalle requerido para la informaci\u00f3n por segmentos en las anotaciones explicativas de los estados financieros.<\/p>\n\n\n\n<p>La Norma requiere la identificaci\u00f3n de cuando los segmentos son una actividad distinguible o un grupo de actividades de una entidad, para los que es apropiado presentar informaci\u00f3n financiera por separado con el prop\u00f3sito de evaluar el rendimiento pasado de la entidad en la consecuci\u00f3n de sus objetivos y tomar decisiones sobre la futura asignaci\u00f3n de recursos. (NICSP 18, 9).<\/p>\n\n\n\n<p>De acuerdo con esta norma, las entidades del sector p\u00fablico identificar\u00e1n como segmentos separados, cada actividad o grupo de actividades identificables para las cuales se deba presenta informaci\u00f3n financiera. Esto ayuda a (a) evaluar el rendimiento pasado de la entidad en el logro de sus objetivos, y (b) tomar decisiones informadas con respecto a la asignaci\u00f3n de recursos de la entidad. Adem\u00e1s, se anima a las entidades a revelar informaci\u00f3n adicional sobre los segmentos sobre los que se informa, tal y como se identifica en esta Norma o seg\u00fan se considere necesario a efectos de rendici\u00f3n de cuentas y toma de decisiones (NICSP 18, 13).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Factores a considerar en la determinaci\u00f3n de la informaci\u00f3n financiera por segmentos<\/h2>\n\n\n\n<p>Los factores que deber\u00e1n considerarse para determinar si los productos (bienes y servicios) est\u00e1n relacionados y deben agruparse como segmentos a efectos de presentaci\u00f3n de la informaci\u00f3n financiera comprenden:<\/p>\n\n\n\n<p>(a) los objetivos operativos principales de la entidad y los bienes, servicios y actividades que se relacionan con el logro de cada uno de dichos objetivos, as\u00ed como la consideraci\u00f3n de si los recursos est\u00e1n asignados y presupuestados sobre la base de grupos de bienes y servicios;<\/p>\n\n\n\n<p>(b) la naturaleza de los bienes o servicios suministrados o las actividades desarrolladas;<\/p>\n\n\n\n<p>(c) la naturaleza de los procesos de producci\u00f3n y\/o de suministro del servicio, y el proceso o mecanismo de distribuci\u00f3n;<\/p>\n\n\n\n<p>(d) el tipo de cliente o consumidor de los bienes o servicios;<\/p>\n\n\n\n<p>(e) la consideraci\u00f3n de si todo esto refleja o no la forma en que la entidad se administra y la informaci\u00f3n financiera se presenta al \u00f3rgano de direcci\u00f3n y la alta administraci\u00f3n; y<\/p>\n\n\n\n<p>(f) si fuera aplicable, la naturaleza del entorno regulatorio (\u00e1mbito ministerial o \u00e1mbito de una autoridad reglamentaria, por ejemplo) o el sector de gobierno (por ejemplo: finanzas, servicios p\u00fablicos o gobierno en su conjunto).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Estudio de caso<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">El caso<\/h3>\n\n\n\n<p>La Entidad (X) -una entidad del sector p\u00fablico que aplica las NICSP- tiene varias filiales y elabora estados financieros consolidados. En los estados financieros consolidados presenta una serie de segmentos, revela informaci\u00f3n sobre los segmentos a nivel de actividad y es auditada de conformidad con las Normas Internacionales de Auditor\u00eda (NIA).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Informaci\u00f3n a revelar<\/h3>\n\n\n\n<p>A continuaci\u00f3n figura la secci\u00f3n relativa a la informaci\u00f3n por segmentos a 31 de diciembre de 2024 y a 31 de diciembre de 2023 de la Entidad (X), cuya actividad principal consiste en segmentos que incluyen ingresos por prestaciones de servicios de transporte terrestre, transporte mar\u00edtimo y otros, as\u00ed como ingresos no derivados de prestaciones de servicio, representados por las subvenciones que recibe del Estado.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Informaci\u00f3n por segmentos<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Total&nbsp;<\/strong><strong>(en miles de libras)<\/strong><\/td><td><strong>Subvenciones (en miles de libras)<\/strong><\/td><td><strong>Otros servicios (en miles de libras)<\/strong><\/td><td><strong>Transporte mar\u00edtimo (en miles de libras)<\/strong><\/td><td><strong>Transporte terrestre (en miles de libras)<\/strong><\/td><td><strong>Descripci\u00f3n<\/strong><\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><strong>31-12-2024<\/strong><\/td><\/tr><tr><td>41 000 000<\/td><td>600 000<\/td><td>3 700 000<\/td><td>22 700 000<\/td><td>14 000 000<\/td><td><strong>Ingresos<\/strong><\/td><\/tr><tr><td>(10 100 000)<\/td><td><\/td><td>(1 100 000)<\/td><td>(6 000 000)<\/td><td>(3 000 000)<\/td><td><strong>Salarios<\/strong><\/td><\/tr><tr><td>(2 500 000)<\/td><td><\/td><td>(700 000)<\/td><td>(300 000)<\/td><td>(1 500 000)<\/td><td><strong>Depreciaci\u00f3n<\/strong><\/td><\/tr><tr><td>13 700 000<\/td><td>600 000<\/td><td>800 000<\/td><td>7 200 000<\/td><td>5 100 000<\/td><td><strong>Super\u00e1vit<\/strong><\/td><\/tr><tr><td><strong>52 000 000&nbsp;<\/strong><\/td><td><\/td><td><strong>10 000 000<\/strong><\/td><td><strong>20 000 000<\/strong><\/td><td><strong>22 000 000<\/strong><\/td><td><strong>Total Activos del segmento<\/strong><\/td><\/tr><tr><td><strong>18 500 000<\/strong><\/td><td><\/td><td><strong>3 000 000<\/strong><\/td><td><strong>500 000<\/strong><\/td><td><strong>15 000 000<\/strong><\/td><td><strong>Total Pasivos del segmento<\/strong><\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><strong>31-12-2023<\/strong><\/td><\/tr><tr><td>39 950 000<\/td><td>550 000<\/td><td>3 750 000<\/td><td>22 650 000<\/td><td>13 000 000<\/td><td><strong>Ingresos<\/strong><\/td><\/tr><tr><td>(9 520 000)<\/td><td><\/td><td>(920 000)<\/td><td>(5 800 000)<\/td><td>(2 800 000)<\/td><td><strong>Salarios<\/strong><\/td><\/tr><tr><td>(2 460 000)<\/td><td><\/td><td>(720 000)<\/td><td>(215 000)<\/td><td>(1 525 000)<\/td><td><strong>Depreciaci\u00f3n<\/strong><\/td><\/tr><tr><td>13 480 000<\/td><td>550 000<\/td><td>830 000<\/td><td>7 300 000<\/td><td>4 800 000<\/td><td><strong>Super\u00e1vit<\/strong><\/td><\/tr><tr><td><strong>29 450 000<\/strong><\/td><td><\/td><td><strong>7 000 000<\/strong><\/td><td><strong>20 300 000<\/strong><\/td><td><strong>2 150 000<\/strong><\/td><td><strong>Total Activos del segmento<\/strong><\/td><\/tr><tr><td><strong>38 700 000<\/strong><\/td><td><\/td><td><strong>4 200 000<\/strong><\/td><td><strong>18 000 000<\/strong><\/td><td><strong>16 500 000<\/strong><\/td><td><strong>Total Pasivos del segmento<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Revelaci\u00f3n de ingresos de los principales grupos de productos y regiones geogr\u00e1ficas<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Total (en miles de libras)<\/strong><\/td><td><strong>Subvenciones (en miles de libras)<\/strong><\/td><td><strong>Otros servicios (en miles de libras)<\/strong><\/td><td><strong>Transporte mar\u00edtimo (en miles de libras)<\/strong><\/td><td><strong>Transporte terrestre (en miles de libras)<\/strong><\/td><td><strong>Descripci\u00f3n<\/strong><\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><strong>31-12-2024<\/strong><\/td><\/tr><tr><td>14 150 000<\/td><td>350 000<\/td><td>2 300 000<\/td><td>11 500 000<\/td><td>10 000 000<\/td><td><strong>\u00c1rea 1<\/strong><\/td><\/tr><tr><td>3 600 000<\/td><td>200 000<\/td><td>1 200 000<\/td><td>10 700 000<\/td><td>2 500 000<\/td><td><strong>\u00c1rea 2<\/strong><\/td><\/tr><tr><td>3 250 000<\/td><td>50 000<\/td><td>200 000<\/td><td>500 000<\/td><td>1 500 000<\/td><td><strong>\u00c1rea 3<\/strong><\/td><\/tr><tr><td><strong>21 000 000&nbsp;<\/strong><\/td><td><strong>600 000<\/strong><\/td><td><strong>3 700 000<\/strong><\/td><td><strong>22 700 000<\/strong><\/td><td><strong>14 000 000<\/strong><\/td><td><strong>Total Ingresos<\/strong><\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><strong>31-12-2023<\/strong><\/td><\/tr><tr><td>12 500 000<\/td><td>250 000<\/td><td>1 900 000<\/td><td>11 150 000<\/td><td>9 200 000&nbsp;<\/td><td><strong>\u00c1rea 1<\/strong><\/td><\/tr><tr><td>13 700 000<\/td><td>200 000<\/td><td>1 100 000<\/td><td>11 200 000<\/td><td>1 200 000<\/td><td><strong>\u00c1rea 2<\/strong><\/td><\/tr><tr><td>3 750 000<\/td><td>100 000<\/td><td>750 000<\/td><td>300 000<\/td><td>2 600 000<\/td><td><strong>\u00c1rea 3<\/strong><\/td><\/tr><tr><td><strong>39 950 000<\/strong><\/td><td><strong>550 000<\/strong><\/td><td><strong>3 750 000<\/strong><\/td><td><strong>22 650 000<\/strong><\/td><td><strong>13 000 000<\/strong><\/td><td><strong>Total Ingresos<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Trabajo de auditor\u00eda<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><em>Materialidad<\/em><\/h4>\n\n\n\n<p>De conformidad con los requerimientos de la Norma Internacional de Auditor\u00eda 320 (NIA 320) y a la luz de la gu\u00eda de procedimientos de auditor\u00eda de la Autoridad Estatal de Rendici\u00f3n de Cuentas (ASA, por sus siglas en ingl\u00e9s), fijamos la materialidad en el 1 % de los activos totales y la materialidad de rendimiento en el 80 %.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><em>Planificaci\u00f3n de la auditor\u00eda de estados financieros<\/em><\/h4>\n\n\n\n<p>La ASA planific\u00f3 la auditor\u00eda de los estados financieros con arreglo a los requerimientos de la NIA 300. Tras identificar y valorar los riesgos de incorrecci\u00f3n material (seg\u00fan los requerimientos de la NIA 315), dise\u00f1amos los procedimientos de auditor\u00eda para dar respuesta a los riesgos valorados (seg\u00fan los requerimientos de la NIA 330). Bas\u00e1ndonos en nuestro juicio profesional, determinamos los procedimientos sustantivos a aplicar:<\/p>\n\n\n\n<p>(a) uso de procedimientos anal\u00edticos como procedimientos sustantivos;<\/p>\n\n\n\n<p>(b) pruebas de detalle.<\/p>\n\n\n\n<p>Clasificamos los riesgos de incorrecci\u00f3n material en la informaci\u00f3n financiera por segmentos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>determinando la administraci\u00f3n de los segmentos para los que se deber\u00eda revelar informaci\u00f3n financiera;<\/li>\n\n\n\n<li>determinando el nivel de riesgo asociado a la informaci\u00f3n revelada;<\/li>\n\n\n\n<li>determinando los procedimientos de auditor\u00eda a aplicar para auditar la informaci\u00f3n por segmentos.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><em>Evidencia de auditor\u00eda<\/em><\/h4>\n\n\n\n<p>La ASA recurri\u00f3 al an\u00e1lisis horizontal y vertical de los estados financieros correspondientes a los segmentos revelados, comparando la informaci\u00f3n financiera de la entidad con:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la informaci\u00f3n comparativa de periodos anteriores;<\/li>\n\n\n\n<li>los resultados previstos por la entidad conforme a los presupuestos aprobados.<\/li>\n<\/ul>\n\n\n\n<p>Llevamos a cabo pruebas de detalle en una muestra de transacciones relacionadas con los datos de los segmentos revelados y obtuvimos las confirmaciones pertinentes, que cumplieron con nuestras garant\u00edas de \u00abintegridad, ocurrencia, exactitud y clasificaci\u00f3n\u00bb. Nos centramos en las transacciones realizadas al final del periodo financiero y al comienzo del siguiente, ya que se consideran como cuestiones susceptibles de aumentar los riesgos de incorrecci\u00f3n material.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><em>Cuestiones clave de la auditor\u00eda<\/em><\/h4>\n\n\n\n<p>La ASA identific\u00f3 la informaci\u00f3n por segmentos como una cuesti\u00f3n clave de la auditor\u00eda seg\u00fan los requerimientos de la NIA 701, dada su importancia cr\u00edtica a efectos de proporcionar informaci\u00f3n sobre el rendimiento de la entidad. Tambi\u00e9n resulta relevante por tratarse de un \u00e1rea en la que aumenta el riesgo de incorrecci\u00f3n material, en particular en lo que respecta al juicio profesional de la direcci\u00f3n a la hora de determinar sobre qu\u00e9 segmentos informar.<\/p>\n\n\n\n<p>Las cuestiones clave de la auditor\u00eda se comunican en una secci\u00f3n separada del informe emitido por un auditor independiente de conformidad con los requerimientos de la NIA 701. Esto podr\u00eda incluir una descripci\u00f3n de la cuesti\u00f3n clave de auditor\u00eda \u00abPresentaci\u00f3n de la informaci\u00f3n financiera por segmentos\u00bb, que incluye:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la raz\u00f3n por la que se considera la informaci\u00f3n financiera por segmentos una cuesti\u00f3n clave de la auditor\u00eda, dejando clara la importancia de presentar dichos datos para valorar el rendimiento en los segmentos, as\u00ed como su repercusi\u00f3n en la transparencia y la rendici\u00f3n de cuentas al suministrar informaci\u00f3n financiera a los \u00f3rganos de supervisi\u00f3n de la entidad y permitirles as\u00ed evaluar el rendimiento y exigir responsabilidades a la direcci\u00f3n;<\/li>\n\n\n\n<li>la manera en la que se va a abordar la revelaci\u00f3n de la informaci\u00f3n financiera por segmentos, explicando la metodolog\u00eda de verificaci\u00f3n de los estados financieros correspondientes a los segmentos revelados y resumiendo brevemente los procedimientos aplicados.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><em>Informe del Auditor Independiente<\/em><\/h4>\n\n\n\n<p>La ASA emiti\u00f3 un informe largo sobre la auditor\u00eda de la Entidad (X) seg\u00fan los requerimientos de las Normas Internacionales de Auditor\u00eda y los requerimientos regulatorios de la propia entidad, establecidos en su reglamento financiero. El informe recog\u00eda:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>una opini\u00f3n no modificada sobre los estados financieros del ejercicio cerrado a 31 de diciembre de 2024, seg\u00fan la NIA 700, con las cuestiones clave de la auditor\u00eda presentadas por separado, tal y como exige la NIA 701;<\/li>\n\n\n\n<li>un resumen ejecutivo de las observaciones de las auditor\u00edas financiera y de rendimiento, comunicado a los \u00f3rganos de direcci\u00f3n y gobernanza (el \u2018Comit\u00e9 de Programa y de Presupuesto\u2019).&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusi\u00f3n:<\/h2>\n\n\n\n<p>La auditor\u00eda de la informaci\u00f3n por segmentos es un componente cr\u00edtico de la fiscalizaci\u00f3n financiera del sector p\u00fablico, que trasciende el mero cumplimiento normativo y potencia la transparencia y la rendici\u00f3n de cuentas. Estas auditor\u00edas facultan a las partes interesadas para evaluar la asignaci\u00f3n de fondos y la eficiencia del gasto, refuerzan la credibilidad de los informes financieros y respaldan una gobernanza financiera racional al velar por el uso \u00e9tico y efectivo de los recursos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La revelaci\u00f3n de los estados financieros se considera un aspecto importante para la mejora de la transparencia y la rendici\u00f3n de cuentas y, por tanto, para la lucha contra la corrupci\u00f3n. Las auditor\u00edas financieras que realizan las Entidades Fiscalizadoras Superiores (EFS) desempe\u00f1an un papel efectivo en la fiscalizaci\u00f3n de esta informaci\u00f3n revelada. En el presente art\u00edculo abordaremos la auditor\u00eda de la informaci\u00f3n a revelar en los informes por segmentos del sector p\u00fablico, presentando un estudio de caso sobre dicha informaci\u00f3n como elemento relevante a efectos de potenciar la transparencia y la rendici\u00f3n de cuentas.<\/p>\n","protected":false},"author":186,"featured_media":37193,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[4503],"content-tags":[1047,1065,1082,1156],"country":[2902],"region":[1337,1338],"section":[932],"coauthors":[3602],"class_list":["post-41639","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-q2-2026","content-tags-effective-audit-reports-es","content-tags-financial-audit-es","content-tags-good-governance-es","content-tags-oversight-es","country-egypt-2-es","region-afrosai-es","region-arabosai-es","section-featured-articles-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auditor\u00eda de la informaci\u00f3n financiera a revelar: mejores pr\u00e1cticas e impacto en los informes por segmentos del sector p\u00fablico - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auditor\u00eda de la informaci\u00f3n financiera a revelar: mejores pr\u00e1cticas e impacto en los informes por segmentos del sector p\u00fablico - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"La revelaci\u00f3n de los estados financieros se considera un aspecto importante para la mejora de la transparencia y la rendici\u00f3n de cuentas y, por tanto, para la lucha contra la corrupci\u00f3n. Las auditor\u00edas financieras que realizan las Entidades Fiscalizadoras Superiores (EFS) desempe\u00f1an un papel efectivo en la fiscalizaci\u00f3n de esta informaci\u00f3n revelada. En el presente art\u00edculo abordaremos la auditor\u00eda de la informaci\u00f3n a revelar en los informes por segmentos del sector p\u00fablico, presentando un estudio de caso sobre dicha informaci\u00f3n como elemento relevante a efectos de potenciar la transparencia y la rendici\u00f3n de cuentas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T20:40:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/11\/1-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Accountability State Authority of Egypt- ASA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/\",\"url\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/\",\"name\":\"Auditor\u00eda de la informaci\u00f3n financiera a revelar: mejores pr\u00e1cticas e impacto en los informes por segmentos del sector p\u00fablico - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/11\/1-4.png\",\"datePublished\":\"2026-06-30T12:19:00+00:00\",\"dateModified\":\"2026-07-14T20:40:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/#primaryimage\",\"url\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/11\/1-4.png\",\"contentUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/11\/1-4.png\",\"width\":1326,\"height\":880,\"caption\":\"Fuente: Adobe Stock Images, FAHMI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auditor\u00eda de la informaci\u00f3n financiera a revelar: mejores pr\u00e1cticas e impacto en los informes por segmentos del sector p\u00fablico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#website\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intosaijournal.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auditor\u00eda de la informaci\u00f3n financiera a revelar: mejores pr\u00e1cticas e impacto en los informes por segmentos del sector p\u00fablico - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/","og_locale":"es_ES","og_type":"article","og_title":"Auditor\u00eda de la informaci\u00f3n financiera a revelar: mejores pr\u00e1cticas e impacto en los informes por segmentos del sector p\u00fablico - INTOSAI Journal","og_description":"La revelaci\u00f3n de los estados financieros se considera un aspecto importante para la mejora de la transparencia y la rendici\u00f3n de cuentas y, por tanto, para la lucha contra la corrupci\u00f3n. Las auditor\u00edas financieras que realizan las Entidades Fiscalizadoras Superiores (EFS) desempe\u00f1an un papel efectivo en la fiscalizaci\u00f3n de esta informaci\u00f3n revelada. En el presente art\u00edculo abordaremos la auditor\u00eda de la informaci\u00f3n a revelar en los informes por segmentos del sector p\u00fablico, presentando un estudio de caso sobre dicha informaci\u00f3n como elemento relevante a efectos de potenciar la transparencia y la rendici\u00f3n de cuentas.","og_url":"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/","og_site_name":"INTOSAI Journal","article_modified_time":"2026-07-14T20:40:03+00:00","og_image":[{"width":1326,"height":880,"url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/11\/1-4.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"9 minutes","Written by":"Accountability State Authority of Egypt- ASA"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/","url":"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/","name":"Auditor\u00eda de la informaci\u00f3n financiera a revelar: mejores pr\u00e1cticas e impacto en los informes por segmentos del sector p\u00fablico - INTOSAI Journal","isPartOf":{"@id":"https:\/\/www.intosaijournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/#primaryimage"},"image":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/#primaryimage"},"thumbnailUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/11\/1-4.png","datePublished":"2026-06-30T12:19:00+00:00","dateModified":"2026-07-14T20:40:03+00:00","breadcrumb":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/#primaryimage","url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/11\/1-4.png","contentUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/11\/1-4.png","width":1326,"height":880,"caption":"Fuente: Adobe Stock Images, FAHMI"},{"@type":"BreadcrumbList","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/auditoria-de-la-informacion-financiera-a-revelar-mejores-practicas-e-impacto-en-los-informes-por-segmentos-del-sector-publico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/es\/"},{"@type":"ListItem","position":2,"name":"Auditor\u00eda de la informaci\u00f3n financiera a revelar: mejores pr\u00e1cticas e impacto en los informes por segmentos del sector p\u00fablico"}]},{"@type":"WebSite","@id":"https:\/\/www.intosaijournal.org\/es\/#website","url":"https:\/\/www.intosaijournal.org\/es\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/www.intosaijournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intosaijournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.intosaijournal.org\/es\/#organization","name":"INTOSAI Journal","url":"https:\/\/www.intosaijournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/41639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/users\/186"}],"version-history":[{"count":3,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/41639\/revisions"}],"predecessor-version":[{"id":42370,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/41639\/revisions\/42370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/media\/37193"}],"wp:attachment":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/media?parent=41639"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-categories?post=41639"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/content-tags?post=41639"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/country?post=41639"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/region?post=41639"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/section?post=41639"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/coauthors?post=41639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}