{"id":37062,"date":"2025-12-11T16:08:20","date_gmt":"2025-12-11T21:08:20","guid":{"rendered":"https:\/\/intosaijournal.org\/?post_type=journal-entry&#038;p=37062"},"modified":"2025-12-16T02:41:17","modified_gmt":"2025-12-16T07:41:17","slug":"el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores","status":"publish","type":"journal-entry","link":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/","title":{"rendered":"El aprovechamiento del an\u00e1lisis en tiempo real para la rendici\u00f3n de cuentas p\u00fablica: la evoluci\u00f3n digital de las Entidades Fiscalizadoras Superiores"},"content":{"rendered":"\n<p><strong>Autor: Emmanouil Kalaintzis<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>I. Del laborioso muestreo a una vigilancia inmediata<\/strong><\/h2>\n\n\n\n<p>Las auditor\u00edas financieras cl\u00e1sicas llegan cuando hace tiempo que el dinero se ha movido. Para cuando se procede a conciliar los libros contables y a presentar los informes, las transferencias fraudulentas suelen estar blanqueadas y su recuperaci\u00f3n ya resulta imposible. Ahora bien, como los datos de las administraciones p\u00fablicas ya circulan por las autopistas digitales \u2014plataformas de la Hacienda P\u00fablica, API fiscales, pasarelas de pago, plataformas e incluso la nube\u2014, cada transacci\u00f3n deja una huella con su sello electr\u00f3nico de tiempo.<\/p>\n\n\n\n<p>Cuando las Entidades Fiscalizadoras Superiores (EFS) introducen estos flujos en motores anal\u00edticos, comprimen un ciclo de auditor\u00eda de meses a minutos. Adem\u00e1s, se puede entrenar el aprendizaje autom\u00e1tico acumulando los datos para agregarlos y adaptarlos a la localizaci\u00f3n de patrones<sup data-fn=\"55c1dcc6-8e81-4526-9481-cdc5036f4ce3\" class=\"fn\"><a id=\"55c1dcc6-8e81-4526-9481-cdc5036f4ce3-link\" href=\"#55c1dcc6-8e81-4526-9481-cdc5036f4ce3\">1<\/a><\/sup>. As\u00ed es posible aflorar y detectar los patrones sospechosos casi en el mismo instante en el que se forman, proporcionando a los auditores la oportunidad de actuar mientras el dinero p\u00fablico a\u00fan se encuentra a su alcance. A medida que las finanzas gubernamentales se van digitalizando por completo, la auditor\u00eda cl\u00e1sica debe adaptarse r\u00e1pidamente, pues de lo contrario los riesgos pueden resultar anacr\u00f3nicos.<\/p>\n\n\n\n<p>Hoy, gracias a la interoperabilidad, las propias interfaces de programaci\u00f3n de aplicaciones (API), en las que se basa el funcionamiento de los sistemas fiscales, bancarios, de contrataci\u00f3n y de la Hacienda P\u00fablica, tambi\u00e9n pueden servir para dar acceso a un flujo continuo de transacciones a las EFS. Mediante el an\u00e1lisis de dichos flujos en busca de anomal\u00edas estad\u00edsticas, los auditores tienen la posibilidad de captar patrones de enriquecimiento il\u00edcito pr\u00e1cticamente en el momento en el que emergen y reducir as\u00ed el margen de maniobra para ocultar o blanquear fondos. Las visualizaciones de datos y los <em>dashboards<\/em> en tiempo real, as\u00ed como las alertas autom\u00e1ticas permiten a las EFS compartir informaci\u00f3n m\u00e1s inmediata con las partes interesadas y, en su caso, con la opini\u00f3n p\u00fablica. Esto contribuye a un proceso de auditor\u00eda m\u00e1s abierto y faculta a la sociedad civil para monitorear el rendimiento del sector p\u00fablico en un entorno din\u00e1mico y basado en datos. Tal y como observ\u00f3 la OCDE en 2024, los sistemas en tiempo real potencian no solo la funci\u00f3n de garant\u00eda, sino tambi\u00e9n la legitimidad externa de la supervisi\u00f3n p\u00fablica, dado que mejoran su visibilidad y posibilitan unas intervenciones m\u00e1s oportunas<sup data-fn=\"00b50994-e8ec-48d8-9412-02c3915c05a3\" class=\"fn\"><a id=\"00b50994-e8ec-48d8-9412-02c3915c05a3-link\" href=\"#00b50994-e8ec-48d8-9412-02c3915c05a3\">2<\/a><\/sup>.<\/p>\n\n\n\n<p>Un sistema de detecci\u00f3n en tiempo real est\u00e1 organizado en capas. Unos canales seguros ingieren primero los flujos de datos fiscales, bancarios, aduaneros y de contrataci\u00f3n. Al tratarse de un ecosistema estratificado, una vez recibidos los datos en bruto, se procede a resolver los alias, dise\u00f1ar los indicadores de riesgo, asignar puntuaciones siguiendo unos modelos, categorizar las alertas y registrar todas las decisiones para garantizar la integridad de la evidencia. Asimismo, permite detectar numerosas variantes, sociedades <em>holding<\/em> y beneficiarios reales, en funci\u00f3n de la cadena de transacciones que se desagrega y mapea para poder revelar las transferencias bancarias, las declaraciones fiscales, las declaraciones de aduana y otras operaciones que completan el cuadro general. Las cifras en bruto son f\u00e1ciles de \u201ctraducir\u201d a indicadores de conducta: tasas de crecimiento inusuales, ratios at\u00edpicas en la composici\u00f3n de grupos de pares, redes de pago de reciente creaci\u00f3n. Los modelos de aprendizaje autom\u00e1tico o los conjuntos de reglas elaborados por expertos asignan una puntuaci\u00f3n a cada evento, clasific\u00e1ndolo seg\u00fan su nivel de riesgo. Al final, un m\u00f3dulo de gesti\u00f3n de casos remite los \u00edtems de mayor riesgo a los auditores humanos, indic\u00e1ndoles con precisi\u00f3n los \u00e1mbitos de riesgo a fin de establecer certeramente el plan de auditor\u00eda. Como es natural, los auditores ejercen la supervisi\u00f3n y tienen la potestad de desestimar una alerta o de darle seguimiento, lo que permite que la ciencia de datos y el criterio profesional vayan de la mano, reforz\u00e1ndose mutuamente.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>II. Desaf\u00edos jur\u00eddicos: reconfigurar el proceso de auditor\u00eda<\/strong><\/strong><\/h2>\n\n\n\n<p>A pesar de sus ventajas, la implantaci\u00f3n de algoritmos plantea unas cuestiones jur\u00eddicas y \u00e9ticas complejas. Estas potentes herramientas anal\u00edticas pueden llegar a abrumar o inducir a error si no son controladas, es decir, si no hay supervisi\u00f3n humana<sup data-fn=\"c0e163ef-0cba-4499-8140-348ace8479d1\" class=\"fn\"><a id=\"c0e163ef-0cba-4499-8140-348ace8479d1-link\" href=\"#c0e163ef-0cba-4499-8140-348ace8479d1\">3<\/a><\/sup>. Un exceso de falsas alarmas desgasta al personal; las brechas de datos ocultos sesgan los modelos; los algoritmos de \u201ccaja negra\u201d entra\u00f1an el riesgo de un tratamiento no homog\u00e9neo; y surgen problem\u00e1ticas relativas a la protecci\u00f3n de los datos personales. La mitigaci\u00f3n de tales riesgos empieza por la transparencia: cada alerta deber\u00eda mostrar la evidencia que la activ\u00f3. La responsabilidad de revisi\u00f3n debe ser jer\u00e1rquica y los registros de acceso tienen que reflejar qui\u00e9n ha accedido a qu\u00e9 y cu\u00e1ndo, preservando la cadena de mando.<\/p>\n\n\n\n<p>Muchas EFS carecen de la infraestructura o la pericia tecnol\u00f3gicas necesarias para implantar sofisticados marcos de auditor\u00eda basados en inteligencia artificial (IA). Adem\u00e1s, a menudo surgen conflictos entre la necesidad de transparencia y la protecci\u00f3n de la confidencialidad comercial o la propiedad intelectual, especialmente cuando se auditan contratistas del sector privado o algoritmos incrustados en sistemas p\u00fablicos. Para abordar estas limitaciones, las EFS tienen que desarrollar estrategias s\u00f3lidas de gobernanza digital, invertir en la creaci\u00f3n de capacidades interdisciplinarias y adoptar principios \u00e9ticos a la hora de dise\u00f1ar el despliegue de herramientas anal\u00edticas en tiempo real. La evoluci\u00f3n digital de las EFS no solo depender\u00e1 de su preparaci\u00f3n tecnol\u00f3gica, sino tambi\u00e9n de su compromiso institucional con la defensa de la integridad, la independencia y los derechos de la ciudadan\u00eda en un escenario de supervisi\u00f3n de r\u00e1pidos cambios.<\/p>\n\n\n\n<p>La Ley de Inteligencia Artificial de la Uni\u00f3n Europea (Ley de IA de la UE), adoptada en julio de 2024, establece un marco jur\u00eddico armonizado para el desarrollo, despliegue y uso de sistemas de inteligencia artificial en todos los Estados miembros. Con un enfoque basado en riesgos, esta ley clasifica los sistemas de IA en cuatro niveles \u2014riesgo inaceptable, alto, limitado y m\u00ednimo\u2014, cada uno de los cuales est\u00e1 asociado a obligaciones de conformidad espec\u00edficas. Los sistemas considerados de alto riesgo, como los que emplean las fuerzas de seguridad, los servicios financieros y la asistencia sanitaria, deben cumplir requisitos muy rigurosos en materia de transparencia, supervisi\u00f3n humana, gesti\u00f3n de riesgos y gobernanza de datos<sup data-fn=\"73e5edac-b165-4331-bb7f-089627d70bc6\" class=\"fn\"><a id=\"73e5edac-b165-4331-bb7f-089627d70bc6-link\" href=\"#73e5edac-b165-4331-bb7f-089627d70bc6\">4<\/a><\/sup>.<\/p>\n\n\n\n<p>Aunque la ley no obliga expl\u00edcitamente a realizar auditor\u00edas de la IA a los proveedores o implantadores, s\u00ed se ajusta firmemente a las pr\u00e1cticas afines a las auditor\u00edas al hacer hincapi\u00e9 en principios como la imparcialidad, la supervisi\u00f3n humana, la precisi\u00f3n y la transparencia. Por otra parte, disposiciones como el art\u00edculo 9 (Sistema de gesti\u00f3n de riesgos) y el art\u00edculo 11 (Documentaci\u00f3n t\u00e9cnica) implican unos requisitos procedimentales y operativos susceptibles de ser satisfechos mediante pr\u00e1cticas de auditor\u00eda estructuradas<sup data-fn=\"f8757570-fc76-42b5-9928-9d3d024e5d1d\" class=\"fn\"><a id=\"f8757570-fc76-42b5-9928-9d3d024e5d1d-link\" href=\"#f8757570-fc76-42b5-9928-9d3d024e5d1d\">5<\/a><\/sup>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>III. Ejemplo de la modernizaci\u00f3n de la EFS de Grecia<\/strong><\/strong><\/h2>\n\n\n\n<p>Las EFS pueden ser llamadas a auditar el uso que hace el sector p\u00fablico de los sistemas de IA, particularmente en \u00e1mbitos como la toma de decisiones automatizada o la asignaci\u00f3n de recursos asistida por IA, pero tambi\u00e9n han de asegurarse de que ellas misma apliquen el an\u00e1lisis basado en la IA respetando las leyes de protecci\u00f3n de datos, la igualdad de las partes y el principio de explicabilidad. El Tribunal de Cuentas de Grecia aporta un enfoque que aborda esas dos caras de la misma moneda. En virtud de la Constituci\u00f3n helena, el Tribunal de Cuentas de Grecia (<em>Elegktiko Synedrio<\/em>) es el tribunal supremo financiero de la Rep\u00fablica Hel\u00e9nica, que funciona como la Entidad Fiscalizadora Superior del Estado y audita el uso de los fondos p\u00fablicos.<\/p>\n\n\n\n<p>En estos momentos, el Tribunal de Cuentas de Grecia est\u00e1 iniciando una nueva era de transformaci\u00f3n digital con la implantaci\u00f3n de su Sistema Integrado de Informaci\u00f3n (SII), una iniciativa de reforma emblem\u00e1tica y financiada por el Mecanismo de Recuperaci\u00f3n y Resiliencia de la Uni\u00f3n Europea. Este proyecto est\u00e1 dise\u00f1ado para modernizar las funciones operativas y judiciales del Tribunal mediante la incrustaci\u00f3n de tecnolog\u00edas digitales y herramientas de inteligencia artificial de vanguardia en su flujo de trabajo diario.<\/p>\n\n\n\n<p>El nuevo sistema introduce funcionalidades como la digitalizaci\u00f3n de extensos archivos judiciales, el tratamiento automatizado de documentos y el desarrollo de un expediente electr\u00f3nico para centralizar todos los elementos procesales en un \u00fanico entorno digital. Y, como elemento crucial: el sistema incluye componentes basados en la IA, tales como la anonimizaci\u00f3n autom\u00e1tica de decisiones, la clasificaci\u00f3n tem\u00e1tica de los casos y la sugerencia en tiempo real de jurisprudencia y normativa pertinentes para respaldar la labor de los jueces. Estas prestaciones no solo buscan acelerar los procesos de resoluci\u00f3n y reducir los retrasos acumulados, sino tambi\u00e9n mejorar la calidad, la coherencia y la responsabilidad de los resultados judiciales. Son herramientas que pretenden apoyar, no sustituir, la discreci\u00f3n judicial, preservando as\u00ed la independencia y la integridad de los procedimientos.<\/p>\n\n\n\n<p>Pero adem\u00e1s, el SII ser\u00e1 interoperable con otras plataformas judiciales y de la administraci\u00f3n p\u00fablica, lo que reducir\u00e1 significativamente las redundancias procesales y permitir\u00e1 un enfoque de la justicia m\u00e1s \u00e1gil y basado en datos. El nuevo portal digital del Tribunal de Cuentas, que se estrena oficialmente el 16 de septiembre de 2025, tambi\u00e9n mejorar\u00e1 la accesibilidad y ofrecer\u00e1 servicios orientados al ciudadano, reflejando un cambio de rumbo m\u00e1s profundo en pos de la transparencia institucional y el compromiso c\u00edvico.<\/p>\n\n\n\n<p>Es este el contexto en el que la evoluci\u00f3n digital del Tribunal de Cuentas de Grecia viene a reforzar el desempe\u00f1o de sus competencias, tanto judiciales como fiscalizadoras. La integraci\u00f3n de sistemas inteligentes facilita una supervisi\u00f3n m\u00e1s oportuna y efectiva, sin perjuicio de la conformidad con los principios de legalidad, proporcionalidad y respeto de los derechos fundamentales. Constituye, pues, un paso decisivo hacia una justicia m\u00e1s moderna, eficiente y responsable.<\/p>\n\n\n\n<p>Por \u00faltimo, y habida cuenta del \u00e9nfasis que la Ley de IA de la UE pone en los derechos fundamentales, la transparencia y la supervisi\u00f3n humana \u2014en particular en el caso de los sistemas de IA de alto riesgo\u2014, es razonable esperar que un Tribunal de Cuentas investido de poderes jurisdiccionales pueda ejercer su competencia para revisar los actos de imputaci\u00f3n en los que intervengan sistemas de IA. En tales casos, el Tribunal estar\u00eda facultado para evaluar si la implantaci\u00f3n del sistema de IA respeta las normas de derechos humanos aplicables, incluidas las garant\u00edas contra la discriminaci\u00f3n, el derecho al debido proceso y los principios de protecci\u00f3n de datos. Esta supervisi\u00f3n se enmarca en el objetivo m\u00e1s amplio de la Ley de IA, a saber, velar por que las tecnolog\u00edas de IA funcionen de conformidad con el marco de derechos fundacionales de la Uni\u00f3n para reforzar as\u00ed la legitimidad y la responsabilidad de la toma de decisiones p\u00fablicas automatizada. En el caso concreto del Tribunal de Cuentas de Grecia, dicha responsabilidad se ve reducida a un m\u00ednimo, ya que funge como un tribunal financiero supremo, provisto de todas las atribuciones necesarias de imparcialidad e independencia y dotado de jueces con competencias para garantizar la indispensable visi\u00f3n de conjunto en materia de solidez jur\u00eddica. Adem\u00e1s, su nuevo Estatuto (Ley n.<sup>o<\/sup> 4820\/2021) y su derecho constitucional de investigaci\u00f3n inmunizan al Tribunal de Cuentas de Grecia y lo facultan para hacer frente de forma efectiva a tales amenazas.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Pasando ahora a la auditor\u00eda de los sistemas de IA usados por los organismos auditados, cabe se\u00f1alar que el Tribunal de Cuentas de Grecia est\u00e1 revisando actualmente el r\u00e9gimen nacional de declaraci\u00f3n de bienes y activos, un sistema que obliga a cientos de miles de funcionarios y cargos p\u00fablicos a revelar anualmente sus ingresos, propiedades y pasivos. El sistema de declaraci\u00f3n de bienes y activos fue reformado recientemente e incluye ahora una moderna plataforma de tramitaci\u00f3n totalmente digital, que acaba de entrar en pleno funcionamiento. Est\u00e1 dise\u00f1ado para extraer informaci\u00f3n de bases de datos fiscales, catastrales y bancarias, creando as\u00ed la base t\u00e9cnica para el an\u00e1lisis de transacciones. El Tribunal de Cuentas de Grecia ha auditado tambi\u00e9n el funcionamiento de este sistema, considerado por la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3micos (OCDE) una herramienta de primer orden para la lucha contra la corrupci\u00f3n en el sector p\u00fablico. Los resultados se publicar\u00e1n en breve, a\u00fan en 2025.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>IV. Conclusi\u00f3n<\/strong><\/h2>\n\n\n\n<p>Muchas jurisdicciones han digitalizado la supervisi\u00f3n (facturaci\u00f3n electr\u00f3nica, declaraciones electr\u00f3nicas), pero siguen dependiendo de un laborioso muestreo para realizar pruebas de integridad y exigir responsabilidades. El an\u00e1lisis continuo de las transacciones cierra esta brecha. Una biblioteca compartida de c\u00f3digo abierto de modelos de indicadores de alerta \u2014detecci\u00f3n de conflictos de intereses, mapeo de colusiones en la contrataci\u00f3n p\u00fablica, seguimiento del \u201cfraude carrusel\u201d de IVA\u2014 permitir\u00eda a las EFS con recursos limitados saltarse a\u00f1os de experimentaci\u00f3n. El an\u00e1lisis de transacciones no sustituye ni al escepticismo profesional ni a la supervisi\u00f3n judicial, sino que los amplifica. Al convertir un torrente de datos digitales en indicadores de alerta plausibles, las EFS consiguen dejar atr\u00e1s la identificaci\u00f3n manual de riesgos y pasar a una vigilancia inmediata.&nbsp;<\/p>\n\n\n\n<p>La lecci\u00f3n es universal: asegure las competencias legales, abra los flujos de datos, combine la auditor\u00eda artesanal con la ciencia de datos e itere con rapidez en el marco de s\u00f3lidos controles \u00e9ticos e intercambie, o, mejor a\u00fan, ponga en com\u00fan las mejores pr\u00e1cticas y la experiencia adquirida en tecnolog\u00edas de la informaci\u00f3n (TI). La recompensa ser\u00e1 un incremento tanto de su capacidad de disuasi\u00f3n como de detecci\u00f3n \u2014 mucho antes de que se seque la tinta del informe de auditor\u00eda. Por ello, cualquier EFS que se plantee emprender este viaje debe empezar por actualizar y blindar su mandato para garantizar el debido proceso.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Notas al pie<\/h2>\n\n\n<ol class=\"wp-block-footnotes\"><li id=\"55c1dcc6-8e81-4526-9481-cdc5036f4ce3\">Iniciativa de Desarrollo de la INTOSAI (IDI) (2023). <em>Understanding the use of Artificial Intelligence in Public Sector Auditing<\/em> (Comprender el uso de la Inteligencia Artificial en la auditor\u00eda gubernamental). <a href=\"#55c1dcc6-8e81-4526-9481-cdc5036f4ce3-link\" aria-label=\"Jump to footnote reference 1\">\u21a9\ufe0e<\/a><\/li><li id=\"00b50994-e8ec-48d8-9412-02c3915c05a3\">OCDE. (2024). <em>Governing with Artificial Intelligence: Are governments ready? <\/em>(Gobernar con la inteligencia artificial: \u00bfest\u00e1n preparados los gobiernos?)<em> OECD AI Papers, No. 20.<\/em> <a href=\"https:\/\/doi.org\/10.1787\/26324bc2-en\">https:\/\/doi.org\/10.1787\/26324bc2-en<\/a>\u00a0 <a href=\"#00b50994-e8ec-48d8-9412-02c3915c05a3-link\" aria-label=\"Jump to footnote reference 2\">\u21a9\ufe0e<\/a><\/li><li id=\"c0e163ef-0cba-4499-8140-348ace8479d1\">\u00a0Papapanagiotou, A., &amp; Zachou, C. (Octubre de 2024). <em>AI and machine learning in public sector auditing: Perspectives from the Hellenic Court of Audit \u2013 A jurisdictional SAI.<\/em> (IA y aprendizaje autom\u00e1tico en la auditoria del sector p\u00fablico: perspectivas del Tribunal de Cuentas de Grecia &#8211; una EFS jurisdiccional). Revista de la ASOSAI. <a href=\"#c0e163ef-0cba-4499-8140-348ace8479d1-link\" aria-label=\"Jump to footnote reference 3\">\u21a9\ufe0e<\/a><\/li><li id=\"73e5edac-b165-4331-bb7f-089627d70bc6\">Servicio de Estudios del Parlamento Europeo. (2021). <em>Artificial Intelligence Act: Risk-Based Approach and Regulatory Framework<\/em> (Ley de Inteligencia Artificial: enfoque basado en riesgos y marco regulador). <a href=\"#73e5edac-b165-4331-bb7f-089627d70bc6-link\" aria-label=\"Jump to footnote reference 4\">\u21a9\ufe0e<\/a><\/li><li id=\"f8757570-fc76-42b5-9928-9d3d024e5d1d\">Servicio de Estudios del Parlamento Europeo. (2021). <em>Artificial Intelligence Act: Initial Appraisal of the Commission&#8217;s Impact Assessment <\/em>(Ley de Inteligencia Artificial: valoraci\u00f3n inicial de la evaluaci\u00f3n de impacto de la Comisi\u00f3n). <a href=\"#f8757570-fc76-42b5-9928-9d3d024e5d1d-link\" aria-label=\"Jump to footnote reference 5\">\u21a9\ufe0e<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Las auditor\u00edas financieras cl\u00e1sicas llegan cuando hace tiempo que el dinero se ha movido. Para cuando se procede a conciliar los libros contables y a presentar los informes, las transferencias fraudulentas suelen estar blanqueadas y su recuperaci\u00f3n ya resulta imposible. Ahora bien, como los datos de las administraciones p\u00fablicas ya circulan por las autopistas digitales \u2014plataformas de la Hacienda P\u00fablica, API fiscales, pasarelas de pago, plataformas e incluso la nube\u2014, cada transacci\u00f3n deja una huella con su sello electr\u00f3nico de tiempo.<\/p>\n","protected":false},"author":380,"featured_media":37040,"template":"","meta":{"_acf_changed":false,"footnotes":"[{\"content\":\"Iniciativa de Desarrollo de la INTOSAI (IDI) (2023). <em>Understanding the use of Artificial Intelligence in Public Sector Auditing<\/em> (Comprender el uso de la Inteligencia Artificial en la auditor\u00eda gubernamental).\",\"id\":\"55c1dcc6-8e81-4526-9481-cdc5036f4ce3\"},{\"content\":\"OCDE. (2024). <em>Governing with Artificial Intelligence: Are governments ready? <\/em>(Gobernar con la inteligencia artificial: \u00bfest\u00e1n preparados los gobiernos?)<em> OECD AI Papers, No. 20.<\/em> <a href=\\\"https:\/\/doi.org\/10.1787\/26324bc2-en\\\">https:\/\/doi.org\/10.1787\/26324bc2-en<\/a>\u00a0\",\"id\":\"00b50994-e8ec-48d8-9412-02c3915c05a3\"},{\"content\":\"\u00a0Papapanagiotou, A., &amp; Zachou, C. (Octubre de 2024). <em>AI and machine learning in public sector auditing: Perspectives from the Hellenic Court of Audit \u2013 A jurisdictional SAI.<\/em> (IA y aprendizaje autom\u00e1tico en la auditoria del sector p\u00fablico: perspectivas del Tribunal de Cuentas de Grecia - una EFS jurisdiccional). Revista de la ASOSAI.\",\"id\":\"c0e163ef-0cba-4499-8140-348ace8479d1\"},{\"content\":\"Servicio de Estudios del Parlamento Europeo. (2021). <em>Artificial Intelligence Act: Risk-Based Approach and Regulatory Framework<\/em> (Ley de Inteligencia Artificial: enfoque basado en riesgos y marco regulador).\",\"id\":\"73e5edac-b165-4331-bb7f-089627d70bc6\"},{\"content\":\"Servicio de Estudios del Parlamento Europeo. (2021). <em>Artificial Intelligence Act: Initial Appraisal of the Commission's Impact Assessment <\/em>(Ley de Inteligencia Artificial: valoraci\u00f3n inicial de la evaluaci\u00f3n de impacto de la Comisi\u00f3n).\",\"id\":\"f8757570-fc76-42b5-9928-9d3d024e5d1d\"}]"},"journal-categories":[4357],"content-tags":[1029,1035,1036,1189],"country":[4260],"region":[1341],"section":[932],"coauthors":[4341],"class_list":["post-37062","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-q3-2025-es","content-tags-data-analytics-es","content-tags-digital-transformation-es","content-tags-digitalization-es","content-tags-real-time-auditing-es","country-grecia","region-eurosai-es","section-featured-articles-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El aprovechamiento del an\u00e1lisis en tiempo real para la rendici\u00f3n de cuentas p\u00fablica: la evoluci\u00f3n digital de las Entidades Fiscalizadoras Superiores - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El aprovechamiento del an\u00e1lisis en tiempo real para la rendici\u00f3n de cuentas p\u00fablica: la evoluci\u00f3n digital de las Entidades Fiscalizadoras Superiores - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"Las auditor\u00edas financieras cl\u00e1sicas llegan cuando hace tiempo que el dinero se ha movido. Para cuando se procede a conciliar los libros contables y a presentar los informes, las transferencias fraudulentas suelen estar blanqueadas y su recuperaci\u00f3n ya resulta imposible. Ahora bien, como los datos de las administraciones p\u00fablicas ya circulan por las autopistas digitales \u2014plataformas de la Hacienda P\u00fablica, API fiscales, pasarelas de pago, plataformas e incluso la nube\u2014, cada transacci\u00f3n deja una huella con su sello electr\u00f3nico de tiempo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T07:41:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/09\/q3_2025_Harnessing-Real-Time-Analytics-for-Public-Accountability-The-Digital-Evolution-of-Supreme-Audit-Institutions.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Emmanouil Kalaintzis\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/\",\"name\":\"El aprovechamiento del an\u00e1lisis en tiempo real para la rendici\u00f3n de cuentas p\u00fablica: la evoluci\u00f3n digital de las Entidades Fiscalizadoras Superiores - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/intosaijournal.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/09\/q3_2025_Harnessing-Real-Time-Analytics-for-Public-Accountability-The-Digital-Evolution-of-Supreme-Audit-Institutions.png\",\"datePublished\":\"2025-12-11T21:08:20+00:00\",\"dateModified\":\"2025-12-16T07:41:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/#primaryimage\",\"url\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/09\/q3_2025_Harnessing-Real-Time-Analytics-for-Public-Accountability-The-Digital-Evolution-of-Supreme-Audit-Institutions.png\",\"contentUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/09\/q3_2025_Harnessing-Real-Time-Analytics-for-Public-Accountability-The-Digital-Evolution-of-Supreme-Audit-Institutions.png\",\"width\":1326,\"height\":880,\"caption\":\"Fuente: Adobe Stock Images, tadamichi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El aprovechamiento del an\u00e1lisis en tiempo real para la rendici\u00f3n de cuentas p\u00fablica: la evoluci\u00f3n digital de las Entidades Fiscalizadoras Superiores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intosaijournal.org\/#website\",\"url\":\"https:\/\/intosaijournal.org\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intosaijournal.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intosaijournal.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intosaijournal.org\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/intosaijournal.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El aprovechamiento del an\u00e1lisis en tiempo real para la rendici\u00f3n de cuentas p\u00fablica: la evoluci\u00f3n digital de las Entidades Fiscalizadoras Superiores - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/","og_locale":"es_ES","og_type":"article","og_title":"El aprovechamiento del an\u00e1lisis en tiempo real para la rendici\u00f3n de cuentas p\u00fablica: la evoluci\u00f3n digital de las Entidades Fiscalizadoras Superiores - INTOSAI Journal","og_description":"Las auditor\u00edas financieras cl\u00e1sicas llegan cuando hace tiempo que el dinero se ha movido. Para cuando se procede a conciliar los libros contables y a presentar los informes, las transferencias fraudulentas suelen estar blanqueadas y su recuperaci\u00f3n ya resulta imposible. Ahora bien, como los datos de las administraciones p\u00fablicas ya circulan por las autopistas digitales \u2014plataformas de la Hacienda P\u00fablica, API fiscales, pasarelas de pago, plataformas e incluso la nube\u2014, cada transacci\u00f3n deja una huella con su sello electr\u00f3nico de tiempo.","og_url":"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/","og_site_name":"INTOSAI Journal","article_modified_time":"2025-12-16T07:41:17+00:00","og_image":[{"width":1326,"height":880,"url":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/09\/q3_2025_Harnessing-Real-Time-Analytics-for-Public-Accountability-The-Digital-Evolution-of-Supreme-Audit-Institutions.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"10 minutes","Written by":"Emmanouil Kalaintzis"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/","url":"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/","name":"El aprovechamiento del an\u00e1lisis en tiempo real para la rendici\u00f3n de cuentas p\u00fablica: la evoluci\u00f3n digital de las Entidades Fiscalizadoras Superiores - INTOSAI Journal","isPartOf":{"@id":"https:\/\/intosaijournal.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/#primaryimage"},"image":{"@id":"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/#primaryimage"},"thumbnailUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/09\/q3_2025_Harnessing-Real-Time-Analytics-for-Public-Accountability-The-Digital-Evolution-of-Supreme-Audit-Institutions.png","datePublished":"2025-12-11T21:08:20+00:00","dateModified":"2025-12-16T07:41:17+00:00","breadcrumb":{"@id":"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/#primaryimage","url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/09\/q3_2025_Harnessing-Real-Time-Analytics-for-Public-Accountability-The-Digital-Evolution-of-Supreme-Audit-Institutions.png","contentUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/09\/q3_2025_Harnessing-Real-Time-Analytics-for-Public-Accountability-The-Digital-Evolution-of-Supreme-Audit-Institutions.png","width":1326,"height":880,"caption":"Fuente: Adobe Stock Images, tadamichi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intosaijournal.org\/es\/journal-entry\/el-aprovechamiento-del-analisis-en-tiempo-real-para-la-rendicion-de-cuentas-publica-la-evolucion-digital-de-las-entidades-fiscalizadoras-superiores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/es\/"},{"@type":"ListItem","position":2,"name":"El aprovechamiento del an\u00e1lisis en tiempo real para la rendici\u00f3n de cuentas p\u00fablica: la evoluci\u00f3n digital de las Entidades Fiscalizadoras Superiores"}]},{"@type":"WebSite","@id":"https:\/\/intosaijournal.org\/#website","url":"https:\/\/intosaijournal.org\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/intosaijournal.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intosaijournal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/intosaijournal.org\/#organization","name":"INTOSAI Journal","url":"https:\/\/intosaijournal.org\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/37062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/users\/380"}],"version-history":[{"count":3,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/37062\/revisions"}],"predecessor-version":[{"id":37621,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/37062\/revisions\/37621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/media\/37040"}],"wp:attachment":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/media?parent=37062"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-categories?post=37062"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/content-tags?post=37062"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/country?post=37062"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/region?post=37062"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/section?post=37062"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/coauthors?post=37062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}