{"id":33254,"date":"2025-04-16T14:54:13","date_gmt":"2025-04-16T18:54:13","guid":{"rendered":"https:\/\/intosaijournal.org\/?post_type=journal-entry&#038;p=33254"},"modified":"2025-04-16T14:54:55","modified_gmt":"2025-04-16T18:54:55","slug":"el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico","status":"publish","type":"journal-entry","link":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/","title":{"rendered":"El Informe P\u00fablico Anual del Tribunal de Cuentas de Francia sobre la acci\u00f3n p\u00fablica para la adaptaci\u00f3n al cambio clim\u00e1tico"},"content":{"rendered":"\n<p>Por Pierre Moscovici, Primer Presidente del Tribunal de Cuentas de Francia<\/p>\n\n\n\n<p>La Constituci\u00f3n francesa confiere al Tribunal de Cuentas de Francia la misi\u00f3n de contribuir a la informaci\u00f3n de la ciudadan\u00eda a trav\u00e9s de sus informes p\u00fablicos. El Informe P\u00fablico Anual (IPA) constituye un instrumento esencial a este respecto. La ley espec\u00edfica que debe tratar \u201c<em>una cuesti\u00f3n de orden p\u00fablico importante sobre la que el Tribunal de Cuentas desea llamar la atenci\u00f3n de los poderes p\u00fablicos y contribuir as\u00ed a informar a los ciudadanos<\/em>\u201d. En su IPA de 2024, el Tribunal examin\u00f3 el tema de la acci\u00f3n p\u00fablica orientada a la adaptaci\u00f3n al cambio clim\u00e1tico.<\/p>\n\n\n\n<p>Esta cuesti\u00f3n afecta a todos los \u00e1mbitos de la acci\u00f3n p\u00fablica. Concierne, en primera instancia, a las administraciones de cualquier naturaleza y de todos los niveles -\u00f3rganos del Estado, autoridades locales, organismos p\u00fablicos nacionales y locales, empresas p\u00fablicas-, pero tambi\u00e9n debe hacer part\u00edcipes a todos los actores de la sociedad: hogares, empresas, la comunidad educativa, las asociaciones e incluso el \u00e1mbito de la investigaci\u00f3n. Ahora bien, en el centro de atenci\u00f3n siempre deben estar los ciudadanos. Nada puede hacerse sin ellos, y, <em>a fortiori<\/em>, contra ellos. Con todo, muchas de las medidas previstas para responder a los efectos del cambio clim\u00e1tico modificar\u00e1n sus condiciones de vida en los aspectos m\u00e1s esenciales: alimentaci\u00f3n, vivienda, transporte, ocio, etc.<\/p>\n\n\n\n<p>La adaptaci\u00f3n al cambio clim\u00e1tico es un asunto complejo. Implica adaptarse a fen\u00f3menos muy diversos (olas de calor, incendios forestales, ciclones, inundaciones, etc.), cuyos efectos se manifiestan a diferentes escalas territoriales y en diferentes horizontes temporales, en un contexto, por lo dem\u00e1s, en constante evoluci\u00f3n. Debido a estas particularidades, la adaptaci\u00f3n al cambio clim\u00e1tico se presta especialmente a que las jurisdicciones financieras ejerzan su papel de terceras partes de confianza ante los responsables de la toma de decisiones y el p\u00fablico.<\/p>\n\n\n\n<p>En los estudios llevados a cabo para el informe participaron las seis c\u00e1maras tem\u00e1ticas del Tribunal de Cuentas y el conjunto de las 17 C\u00e1maras Regionales y Territoriales de Cuentas. La mayor\u00eda de ellas se centr\u00f3 en las pol\u00edticas compartidas entre el Estado y las autoridades locales y fueron dise\u00f1adas y realizadas con vistas a dar respuesta a las grandes preguntas que se hacen los franceses cuando se trata de adaptar sus estilos de vida, su entorno y sus actividades.<\/p>\n\n\n\n<p>La primera es qu\u00e9 esperar concretamente y en qu\u00e9 plazos: quieren comprender los motivos subyacentes y prever las consecuencias del cambio clim\u00e1tico para su vida cotidiana. Tambi\u00e9n se plantean c\u00f3mo se determinar\u00e1n, decidir\u00e1n y repartir\u00e1n entre todos los actores implicados los esfuerzos necesarios para adaptarse al cambio clim\u00e1tico: la adaptaci\u00f3n no debe enfocarse \u00fanicamente desde un punto de vista t\u00e9cnico, sino que tambi\u00e9n reviste una dimensi\u00f3n democr\u00e1tica. Finalmente, y ante la complejidad de la adaptaci\u00f3n y la magnitud de su coste, en un momento en el que la situaci\u00f3n de las finanzas p\u00fablicas es cada vez m\u00e1s preocupante, se preguntan c\u00f3mo definir y aplicar soluciones adecuadas y sostenibles: \u00bfqu\u00e9 se puede hacer eficazmente con el menor coste posible?<\/p>\n\n\n\n<p>Partiendo de esta perspectiva, las jurisdicciones financieras abordaron en un primer paso tres temas transversales: el lugar y el papel de la investigaci\u00f3n p\u00fablica en la adaptaci\u00f3n al cambio clim\u00e1tico, el papel de las instituciones financieras y bancarias en la adaptaci\u00f3n de la econom\u00eda al cambio clim\u00e1tico y la contribuci\u00f3n de la Agencia Francesa de Desarrollo (AFD) en la adaptaci\u00f3n al cambio clim\u00e1tico en los pa\u00edses en desarrollo.<\/p>\n\n\n\n<p>Asimismo, las jurisdicciones financieras analizaron el impacto del cambio clim\u00e1tico en la vida diaria de los franceses y en las grandes infraestructuras p\u00fablicas. A estos efectos, examinaron tanto la adaptaci\u00f3n de viviendas y centros urbanos como la integraci\u00f3n de esta cuesti\u00f3n en la pol\u00edtica de vivienda del Estado. Integrar la consideraci\u00f3n de las consecuencias del cambio clim\u00e1tico en la gesti\u00f3n de centrales nucleares e hidroel\u00e9ctricas, redes de transporte y distribuci\u00f3n de energ\u00eda el\u00e9ctrica o en la red ferroviaria, tanto en t\u00e9rminos de explotaci\u00f3n como de inversi\u00f3n, tambi\u00e9n representa un reto importante y fue objeto de indagaciones espec\u00edficas. La situaci\u00f3n particular del Ministerio de las Fuerzas Armadas de Francia se estudi\u00f3 desde esta misma \u00f3ptica.<\/p>\n\n\n\n<p>Las consecuencias del cambio clim\u00e1tico tambi\u00e9n afectan al entorno natural en el que viven y trabajan los franceses. En este sentido, las jurisdicciones financieras analizaron la forma en la que se anticipan y abordan estos efectos en la gesti\u00f3n de bosques y costas, as\u00ed como en la prevenci\u00f3n de desastres naturales relacionados con el clima en los territorios de ultramar y en la protecci\u00f3n de las personas vulnerables frente a las olas de calor. Del mismo modo, se interesaron por las posibilidades de adaptaci\u00f3n al cambio clim\u00e1tico de los cultivos de cereales y de las estaciones de esqu\u00ed alpino.<\/p>\n\n\n\n<p>De toda esta labor se pueden extraer cuatro lecciones clave.<\/p>\n\n\n\n<p>La primera es la necesidad de conocer mejor los efectos del cambio clim\u00e1tico, los riesgos a los que adaptarnos y su magnitud. Debemos optimizar los datos necesarios para unas previsiones m\u00e1s precisas y fiables, as\u00ed como adaptar las normas vigentes para que contemplen la evoluci\u00f3n de los riesgos. En estos tres planos (datos, previsiones, normas), la labor de las jurisdicciones financieras ha puesto de manifiesto lo mucho que queda por hacer. Cabe se\u00f1alar, por ejemplo, que las herramientas destinadas al inventario y diagn\u00f3stico del estado de alrededor de 200.000 edificios que componen el parque inmobiliario del Estado a\u00fan se encuentran en fase de despliegue y solo proporcionan datos incompletos sobre dos terceras partes del mismo. Otra circunstancia constatada por las jurisdicciones financieras en este contexto es que las predicciones meteorol\u00f3gicas realizadas para los territorios de ultramar son de peor calidad que las de la Francia continental, a pesar de que estos territorios est\u00e1n m\u00e1s expuestos a riesgos y son m\u00e1s vulnerables debido a la concentraci\u00f3n de la poblaci\u00f3n en el litoral y a la elevada proporci\u00f3n de viviendas precarias.&nbsp;<\/p>\n\n\n\n<p>La segunda lecci\u00f3n clave concierne la informaci\u00f3n a la ciudadan\u00eda y a los responsables de la toma de decisiones sobre los retos de la adaptaci\u00f3n. Informar a la poblaci\u00f3n acerca de los riesgos y las decisiones a tomar, pero tambi\u00e9n sobre las oportunidades que ofrecen las medidas de adaptaci\u00f3n, es la condici\u00f3n <em>sine qua non<\/em> para que la opini\u00f3n p\u00fablica apoye el enfoque: para que el despliegue de las medidas sea eficaz debe ir precedido de una intensa labor de persuasi\u00f3n sobre su necesidad y sus beneficios. As\u00ed, por ejemplo, la financiaci\u00f3n de proyectos de reforma integral que no se limiten a cambiar los sistemas de calefacci\u00f3n, sino a mejorar tambi\u00e9n la ventilaci\u00f3n, el aislamiento y la protecci\u00f3n frente al sol de las viviendas, permite tanto elevar el confort de los residentes como animar a las empresas constructoras a contratar a profesionales cualificados para llevar a cabo este tipo de trabajos.<\/p>\n\n\n\n<p>Las investigaciones de las jurisdicciones financieras francesas tambi\u00e9n han evidenciado la necesidad de una acci\u00f3n p\u00fablica que desarrolle una estrategia coherente y coordinada, es decir, que planifique la adaptaci\u00f3n de la sociedad al cambio clim\u00e1tico. De entrada, es preciso conciliar los objetivos de adaptaci\u00f3n con los de muchas otras pol\u00edticas p\u00fablicas &#8211; por ejemplo, con el deseo de los representantes electos y las poblaciones locales en zonas tur\u00edsticas como las regiones de monta\u00f1a o las zonas costeras de preservar su modelo econ\u00f3mico durante el mayor tiempo posible. Igualmente, hemos de establecer una aut\u00e9ntica cultura de planificaci\u00f3n y gesti\u00f3n de riesgos, desplegando los correspondientes instrumentos de planificaci\u00f3n a la escala territorial adecuada y, en los numerosos \u00e1mbitos en los que intervienen varios actores, coordinando dichos instrumentos entre s\u00ed. La implementaci\u00f3n de una planificaci\u00f3n rigurosa y acertada es, en efecto, una condici\u00f3n necesaria, pero no suficiente, de cara a una acci\u00f3n eficaz: tambi\u00e9n hace falta un \u201cpiloto\u201d que arbitre y coordine las acciones de estos m\u00faltiples actores. Por su parte, el Estado debe desempe\u00f1ar plenamente su papel de estratega, consistente en fijar objetivos claros y definir una hoja de ruta para su consecuci\u00f3n.<\/p>\n\n\n\n<p>Por \u00faltimo, las diecis\u00e9is encuestas que realizaron las jurisdicciones financieras han puesto de manifiesto toda la magnitud del desaf\u00edo que supone financiar las pol\u00edticas de adaptaci\u00f3n. En un contexto presupuestario ajustado, este desaf\u00edo solo cabe afrontarlo haciendo de la b\u00fasqueda de la eficiencia -es decir, de la eficacia al menor coste- una prioridad absoluta. En este sentido, el informe advierte de los riesgos de una mala adaptaci\u00f3n, inherentes a la aplicaci\u00f3n de medidas de emergencia (como la dependencia excesiva del aire acondicionado, el despliegue sistem\u00e1tico de ca\u00f1ones de producci\u00f3n de nieve artificial en las estaciones de deportes de invierno o la reposici\u00f3n peri\u00f3dica de arena en las playas amenazadas por la erosi\u00f3n mar\u00edtima), que son eficaces a corto plazo, pero muy costosas a medio y largo plazo. Evidentemente, el papel de la investigaci\u00f3n cient\u00edfica es fundamental para encontrar soluciones adecuadas y ayudar a los actores p\u00fablicos a determinar los m\u00e9todos y el calendario oportunos para su aplicaci\u00f3n. Por otra parte, tenemos que mejorar en la evaluaci\u00f3n de los costes de adaptaci\u00f3n que con demasiada frecuencia sigue siendo incompleta o inexistente. Fijar correctamente los \u201cprecios reales\u201d constituye, de hecho, un elemento de juicio esencial a la hora de definir y materializar soluciones financieramente sostenibles. Sin embargo, la adaptaci\u00f3n no tiene por qu\u00e9 implicar forzosamente un nuevo gasto p\u00fablico. Existen otros mecanismos a los que recurrir, como alentar a los actores a pasar a la acci\u00f3n y responsabilizarlos m\u00e1s.<\/p>\n\n\n\n<p>Estas lecciones dibujan un panorama exigente cara al futuro, pero que en absoluto es desesperanzador: en la mayor\u00eda de los sectores examinados, sin duda queda mucho por hacer, pero ya hay conciencia de la urgencia de la adaptaci\u00f3n y, en mayor o menor medida, los actores p\u00fablicos han empezado a organizarse al respecto. El Tribunal de Cuentas de Francia, por su parte, ha decidido acompa\u00f1ar este proceso elaborando un informe anual sobre la transici\u00f3n ecol\u00f3gica, cuya primera edici\u00f3n se publicar\u00e1 en septiembre de 2025.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Constituci\u00f3n francesa confiere al Tribunal de Cuentas de Francia la misi\u00f3n de contribuir a la informaci\u00f3n de la ciudadan\u00eda a trav\u00e9s de sus informes p\u00fablicos. El Informe P\u00fablico Anual (IPA) constituye un instrumento esencial a este respecto. La ley espec\u00edfica que debe tratar \u201cuna cuesti\u00f3n de orden p\u00fablico importante sobre la que el Tribunal de Cuentas desea llamar la atenci\u00f3n de los poderes p\u00fablicos y contribuir as\u00ed a informar a los ciudadanos\u201d. En su IPA de 2024, el Tribunal examin\u00f3 el tema de la acci\u00f3n p\u00fablica orientada a la adaptaci\u00f3n al cambio clim\u00e1tico.<\/p>\n","protected":false},"author":248,"featured_media":33202,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[4043],"content-tags":[942,2683,3837,1055,1227,1228],"country":[3164],"region":[1341],"section":[915],"coauthors":[3815],"class_list":["post-33254","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-q1-2025-es","content-tags-annual-report-es","content-tags-cambioclimatico","content-tags-competencias-jurisdiccionales","content-tags-environmental-auditing-es","content-tags-strategic-plan-es","content-tags-strategic-planning-es","country-france-es","region-eurosai-es","section-editorial-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Informe P\u00fablico Anual del Tribunal de Cuentas de Francia sobre la acci\u00f3n p\u00fablica para la adaptaci\u00f3n al cambio clim\u00e1tico - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Informe P\u00fablico Anual del Tribunal de Cuentas de Francia sobre la acci\u00f3n p\u00fablica para la adaptaci\u00f3n al cambio clim\u00e1tico - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"La Constituci\u00f3n francesa confiere al Tribunal de Cuentas de Francia la misi\u00f3n de contribuir a la informaci\u00f3n de la ciudadan\u00eda a trav\u00e9s de sus informes p\u00fablicos. El Informe P\u00fablico Anual (IPA) constituye un instrumento esencial a este respecto. La ley espec\u00edfica que debe tratar \u201cuna cuesti\u00f3n de orden p\u00fablico importante sobre la que el Tribunal de Cuentas desea llamar la atenci\u00f3n de los poderes p\u00fablicos y contribuir as\u00ed a informar a los ciudadanos\u201d. En su IPA de 2024, el Tribunal examin\u00f3 el tema de la acci\u00f3n p\u00fablica orientada a la adaptaci\u00f3n al cambio clim\u00e1tico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-16T18:54:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/02\/Pierre-Moscovici-editorial-Q1-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Pierre Moscovici\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/\",\"url\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/\",\"name\":\"El Informe P\u00fablico Anual del Tribunal de Cuentas de Francia sobre la acci\u00f3n p\u00fablica para la adaptaci\u00f3n al cambio clim\u00e1tico - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/intosaijournal.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/02\/Pierre-Moscovici-editorial-Q1-2025.png\",\"datePublished\":\"2025-04-16T18:54:13+00:00\",\"dateModified\":\"2025-04-16T18:54:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/#primaryimage\",\"url\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/02\/Pierre-Moscovici-editorial-Q1-2025.png\",\"contentUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/02\/Pierre-Moscovici-editorial-Q1-2025.png\",\"width\":1326,\"height\":880,\"caption\":\"Pierre Moscovici, primer presidente del Tribunal de Cuentas franc\u00e9s. Fuente: Tribunal de Cuentas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Informe P\u00fablico Anual del Tribunal de Cuentas de Francia sobre la acci\u00f3n p\u00fablica para la adaptaci\u00f3n al cambio clim\u00e1tico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intosaijournal.org\/#website\",\"url\":\"https:\/\/intosaijournal.org\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intosaijournal.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intosaijournal.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intosaijournal.org\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/intosaijournal.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Informe P\u00fablico Anual del Tribunal de Cuentas de Francia sobre la acci\u00f3n p\u00fablica para la adaptaci\u00f3n al cambio clim\u00e1tico - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/","og_locale":"es_ES","og_type":"article","og_title":"El Informe P\u00fablico Anual del Tribunal de Cuentas de Francia sobre la acci\u00f3n p\u00fablica para la adaptaci\u00f3n al cambio clim\u00e1tico - INTOSAI Journal","og_description":"La Constituci\u00f3n francesa confiere al Tribunal de Cuentas de Francia la misi\u00f3n de contribuir a la informaci\u00f3n de la ciudadan\u00eda a trav\u00e9s de sus informes p\u00fablicos. El Informe P\u00fablico Anual (IPA) constituye un instrumento esencial a este respecto. La ley espec\u00edfica que debe tratar \u201cuna cuesti\u00f3n de orden p\u00fablico importante sobre la que el Tribunal de Cuentas desea llamar la atenci\u00f3n de los poderes p\u00fablicos y contribuir as\u00ed a informar a los ciudadanos\u201d. En su IPA de 2024, el Tribunal examin\u00f3 el tema de la acci\u00f3n p\u00fablica orientada a la adaptaci\u00f3n al cambio clim\u00e1tico.","og_url":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/","og_site_name":"INTOSAI Journal","article_modified_time":"2025-04-16T18:54:55+00:00","og_image":[{"width":1326,"height":880,"url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/02\/Pierre-Moscovici-editorial-Q1-2025.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"1 minute","Written by":"Pierre Moscovici"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/","url":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/","name":"El Informe P\u00fablico Anual del Tribunal de Cuentas de Francia sobre la acci\u00f3n p\u00fablica para la adaptaci\u00f3n al cambio clim\u00e1tico - INTOSAI Journal","isPartOf":{"@id":"https:\/\/intosaijournal.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/#primaryimage"},"image":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/#primaryimage"},"thumbnailUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/02\/Pierre-Moscovici-editorial-Q1-2025.png","datePublished":"2025-04-16T18:54:13+00:00","dateModified":"2025-04-16T18:54:55+00:00","breadcrumb":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/#primaryimage","url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/02\/Pierre-Moscovici-editorial-Q1-2025.png","contentUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/02\/Pierre-Moscovici-editorial-Q1-2025.png","width":1326,"height":880,"caption":"Pierre Moscovici, primer presidente del Tribunal de Cuentas franc\u00e9s. Fuente: Tribunal de Cuentas"},{"@type":"BreadcrumbList","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/el-informe-publico-anual-del-tribunal-de-cuentas-de-francia-sobre-la-accion-publica-para-la-adaptacion-al-cambio-climatico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/es\/"},{"@type":"ListItem","position":2,"name":"El Informe P\u00fablico Anual del Tribunal de Cuentas de Francia sobre la acci\u00f3n p\u00fablica para la adaptaci\u00f3n al cambio clim\u00e1tico"}]},{"@type":"WebSite","@id":"https:\/\/intosaijournal.org\/#website","url":"https:\/\/intosaijournal.org\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/intosaijournal.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intosaijournal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/intosaijournal.org\/#organization","name":"INTOSAI Journal","url":"https:\/\/intosaijournal.org\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/33254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/users\/248"}],"version-history":[{"count":2,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/33254\/revisions"}],"predecessor-version":[{"id":33256,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/33254\/revisions\/33256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/media\/33202"}],"wp:attachment":[{"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/media?parent=33254"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-categories?post=33254"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/content-tags?post=33254"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/country?post=33254"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/region?post=33254"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/section?post=33254"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/intosaijournal.org\/es\/wp-json\/wp\/v2\/coauthors?post=33254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}