{"id":41716,"date":"2026-06-30T12:15:00","date_gmt":"2026-06-30T16:15:00","guid":{"rendered":"https:\/\/intosaijournal.org\/?post_type=journal-entry&#038;p=41716"},"modified":"2026-07-14T15:28:03","modified_gmt":"2026-07-14T19:28:03","slug":"pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae","status":"publish","type":"journal-entry","link":"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/","title":{"rendered":"Pr\u00fcfungen der Rechnungsf\u00fchrung und Mechanismen f\u00fcr eine gute Verwaltung \u00f6ffentlicher Mittel: F\u00f6rderung von Rechenschaftspflicht, Transparenz und b\u00fcrgerlichem Vertrauen durch Aufsicht sowie bew\u00e4hrte Verfahren"},"content":{"rendered":"\n<p>Autorin: May Al-Roomi \u2013 leitende Pr\u00fcferin f\u00fcr Informationssysteme \u2013 Oberste Rechnungskontrollbeh\u00f6rde Kuwait<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Einleitung<\/h2>\n\n\n\n<p>F\u00fcr eine gute Regierungsf\u00fchrung m\u00fcssen \u00f6ffentliche Gelder transparent und effizient verwaltet werden. Pr\u00fcfungen der Rechnungsf\u00fchrung und Aufsichtsmechanismen haben zunehmend an Bedeutung gewonnen, da das Vertrauen der \u00d6ffentlichkeit eng mit finanzieller Rechenschaftspflicht verkn\u00fcpft ist. Diese Pr\u00fcfungen und Mechanismen verfolgen zwei Hauptziele: die Aufdeckung sowie Verhinderung von Korruption und Misswirtschaft sowie die F\u00f6rderung von Transparenz und die St\u00e4rkung von Institutionen, um B\u00fcrgerinnen und B\u00fcrgern greifbare Nutzen zu verschaffen.<\/p>\n\n\n\n<p><br>Dieser Beitrag befasst sich mit den fachlichen und praktischen Aspekten von Pr\u00fcfungen der Rechnungsf\u00fchrung sowie anderen Mechanismen zur Regulierung \u00f6ffentlicher Gelder. Darin werden bew\u00e4hrte Verfahren f\u00fcr Pr\u00fcfungen der Rechnungsf\u00fchrung im \u00f6ffentlichen Sektor, die Rolle von Pr\u00fcfungen im Kampf gegen Korruption sowie die Rahmenbedingungen zur F\u00f6rderung von Rechenschaftspflicht erl\u00e4utert. Au\u00dferdem werden Beispiele daf\u00fcr genannt, wie die Verfahren im Rahmen von Pr\u00fcfungen der Rechnungsf\u00fchrung zur Verbesserung der Regierungsf\u00fchrung sowie des Wohlergehens der B\u00fcrgerinnen und B\u00fcrger beitragen k\u00f6nnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Rolle von Pr\u00fcfungen der Rechnungsf\u00fchrung in der \u00f6ffentlichen Verwaltung<\/h2>\n\n\n\n<p>Pr\u00fcfungen der Rechnungsf\u00fchrung k\u00f6nnen als systematische \u00dcberpr\u00fcfungen \u00f6ffentlicher Rechnungsabschl\u00fcsse und Arbeitsabl\u00e4ufe definiert werden, im Zuge derer ermittelt wird, ob gesetzliche Vorschriften, regulatorische Normen und ethische Grunds\u00e4tze eingehalten werden. Diese Pr\u00fcfungen unterst\u00fctzen den \u00f6ffentlichen Sektor dabei, folgende Ziele zu erreichen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00dcberpr\u00fcfung der Finanzberichterstattung auf ihre Richtigkeit, um deren Integrit\u00e4t zu wahren.<\/li>\n\n\n\n<li>Minimierung von Betrug, Misswirtschaft und Fehlverhalten durch die Gew\u00e4hrleistung einer genauen \u00dcberpr\u00fcfung von Finanztransaktionen.<\/li>\n\n\n\n<li>Bessere Orientierung bei finanziellen Entscheidungen, was zu einer optimierten Mittelverteilung f\u00fchrt.<\/li>\n\n\n\n<li>F\u00f6rderung der Transparenz durch \u00f6ffentliche Zug\u00e4nglichkeit der Pr\u00fcfungsergebnisse.<\/li>\n<\/ul>\n\n\n\n<p>Die Umfrage der Organisation f\u00fcr wirtschaftliche Zusammenarbeit und Entwicklung (OECD) aus dem Jahr&nbsp;2024 zum Thema \u201eDrivers of Trust in Public Institutions\u201c (dt. etwa \u201eFaktoren f\u00fcr das Vertrauen in staatliche Institutionen\u201c) zeigt zusammen mit anderen Studien, dass das Vertrauen der \u00d6ffentlichkeit in die Regierung in direktem Zusammenhang mit Ma\u00dfnahmen zu Transparenz und Rechenschaftspflicht steht. Starke Systeme f\u00fcr Pr\u00fcfungen der Rechnungsf\u00fchrung bilden eines der Schl\u00fcsselelemente unter diesen Ma\u00dfnahmen. Die in Abbildung&nbsp;1 illustrierten Daten zeigen, dass L\u00e4nder mit wirksamen Pr\u00fcfungssystemen ein h\u00f6heres Ma\u00df an \u00f6ffentlichem Vertrauen genie\u00dfen, w\u00e4hrend Systeme mit schwachen Pr\u00fcfungsans\u00e4tzen tendenziell zu niedrigeren Vertrauenswerten f\u00fchren.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"994\" height=\"660\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.001.jpeg\" alt=\"\" class=\"wp-image-41718\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.001.jpeg 994w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.001-300x199.jpeg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.001-768x510.jpeg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.001-193x128.jpeg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.001-310x206.jpeg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.001-467x310.jpeg 467w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.001-426x282.jpeg 426w\" sizes=\"auto, (max-width: 994px) 100vw, 994px\" \/><figcaption class=\"wp-element-caption\">Abbildung\u00a01: Verteilung des \u00f6ffentlichen Vertrauens in nationale Regierungen (OECD, 2024)<\/figcaption><\/figure>\n\n\n\n<p>Oberste Rechnungskontrollbeh\u00f6rden (ORKB) sollten gemeinsam mit nationalen Rechnungskontrollbeh\u00f6rden unabh\u00e4ngige Pr\u00fcfungen staatlicher Stellen durchf\u00fchren. Die Exekutive muss weiterhin getrennt von diesen Institutionen bleiben. Denn eine solche Unabh\u00e4ngigkeit gew\u00e4hrleistet die Objektivit\u00e4t und Glaubw\u00fcrdigkeit der Pr\u00fcft\u00e4tigkeiten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bew\u00e4hrte Verfahren f\u00fcr die Durchf\u00fchrung von Pr\u00fcfungen der Rechnungsf\u00fchrung im \u00f6ffentlichen Sektor<\/h2>\n\n\n\n<p>Die folgenden bew\u00e4hrten Verfahren sollten zur Anwendung kommen, um die Wirkung von Pr\u00fcfungen der Rechnungsf\u00fchrung zu maximieren:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Einhaltung internationaler Normen<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Der \u00f6ffentliche Sektor muss die Internationalen Normen f\u00fcr Oberste Rechnungskontrollbeh\u00f6rden (ISSAI) der INTOSAI \u00fcbernehmen, da diese Normen Leitlinien f\u00fcr die Planung, Durchf\u00fchrung und Nachverfolgung von Pr\u00fcfungen sowie die entsprechende Berichterstattung enthalten und somit erm\u00f6glichen, einheitliche und glaubw\u00fcrdige Pr\u00fcfungspraktiken zu etablieren.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Risikobasierte Pr\u00fcfungsplanung<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Pr\u00fcferinnen und Pr\u00fcfer sollten ihre Pr\u00fcfungen auf Bereiche, welche die h\u00f6chsten Risiken aufweisen, fokussieren, anstatt in allen F\u00e4llen dieselben Verfahren anzuwenden. So k\u00f6nnte das Pr\u00fcfungspersonal umfangreiche Beschaffungsvertr\u00e4ge, Infrastrukturprojekte und F\u00f6rdermittelvergaben genauer unter die Lupe nehmen, da in diesen Bereichen ein h\u00f6heres Risiko f\u00fcr Misswirtschaft oder Unregelm\u00e4\u00dfigkeiten besteht.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Zeitnahe und zug\u00e4ngliche Berichterstattung<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Pr\u00fcfungsberichte m\u00fcssen uneingeschr\u00e4nkt zug\u00e4nglich sein und zeitnah ver\u00f6ffentlicht werden. Die Verst\u00e4ndlichkeit solcher Berichte sollte durch Zusammenfassungen und visuelle Darstellungen verbessert werden, damit auch nicht-fachkundige Stakeholder die Informationen besser nachvollziehen k\u00f6nnen.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Stakeholdereinbindung<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Pr\u00fcferinnen und Pr\u00fcfer sollten an Treffen mit gesetzgebenden Organen, zivilgesellschaftlichen Gruppen sowie Medienvertreterinnen und -vertretern teilnehmen, um ihre Erkenntnisse zu erl\u00e4utern und \u00f6ffentliche Debatten \u00fcber die Pr\u00fcfungsergebnisse anzuregen. Dies f\u00f6rdert Rechenschaftspflicht und f\u00fchrt dazu, dass sich die Wirkung der Pr\u00fcfungen \u00fcber Fachkreise hinaus erstreckt.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Robuste Follow-up-Mechanismen<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Pr\u00fcfungen sollten nicht mit einem Bericht enden. Oberste Rechnungskontrollbeh\u00f6rden (ORKB) m\u00fcssen Monitoringsysteme einrichten, um Pr\u00fcfungsempfehlungen anhand von Leistungskennzahlen und festgelegten Zeitpl\u00e4nen kontinuierlich nachverfolgen zu k\u00f6nnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pr\u00fcfungen als Hilfsmittel zur Bek\u00e4mpfung von Korruption und Misswirtschaft<\/h2>\n\n\n\n<p>Korruption wie Misswirtschaft vermindern \u00f6ffentliche Ressourcen, untergraben das Vertrauen der \u00d6ffentlichkeit und behindern Fortschritt. Pr\u00fcfungen der Rechnungsf\u00fchrung fungieren als erste Verteidigungslinie gegen solche Bedrohungen, indem sie unter anderem folgende grundlegende Funktionen erf\u00fcllen:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Aufdeckung von Unregelm\u00e4\u00dfigkeiten: <\/strong>Pr\u00fcfungen k\u00f6nnen Anomalien in den Buchhaltungsunterlagen aufdecken, darunter falsche Angaben, nicht genehmigte Ausgaben und schwache interne Kontrollen. Die Ermittlung solcher Probleme f\u00fchrt dann zu weiteren Nachforschungen, m\u00f6glichen Strafverfolgungen und Reformma\u00dfnahmen.<\/li>\n\n\n\n<li><strong>St\u00e4rkung interner Kontrollen: <\/strong>Pr\u00fcfungsempfehlungen beziehen sich h\u00e4ufig auf die Verbesserungen interner Kontrollsysteme. Dazu geh\u00f6ren Aufgabentrennung, bessere Dokumentation und ordnungsgem\u00e4\u00dfe Genehmigungsverfahren \u2013 alles M\u00f6glichkeiten, um Betrug zu verringern.<\/li>\n\n\n\n<li><strong>F\u00f6rderung einer Kultur der Integrit\u00e4t: <\/strong>Mit der Zeit f\u00fchrt die konsequente Durchf\u00fchrung von Pr\u00fcfungen zu einer Kultur der Rechenschaftspflicht in \u00f6ffentlichen Einrichtungen. Mitarbeiterinnen und Mitarbeiter legen mehr Vorsicht und Sorgfalt an den Tag, da ihre Arbeitst\u00e4tigkeiten unabh\u00e4ngigen Beurteilungen und internen \u00dcberpr\u00fcfungen unterzogen werden k\u00f6nnen.<\/li>\n\n\n\n<li><strong>Unterst\u00fctzung rechtlicher und disziplinarischer Ma\u00dfnahmen: <\/strong>Pr\u00fcfungen, die illegale Aktivit\u00e4ten aufdecken, erm\u00f6glichen rechtliche Konsequenzen und die Verh\u00e4ngung von Verwaltungsstrafen. Dies st\u00e4rkt die Rechtsstaatlichkeit und signalisiert eine Nulltoleranz-Politik gegen\u00fcber dem Missbrauch \u00f6ffentlicher \u00c4mter.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Mechanismen und Rahmenbedingungen f\u00fcr eine rechenschaftspflichtige \u00f6ffentliche Mittelverwaltung<\/h2>\n\n\n\n<p>Pr\u00fcfungen der Rechnungsf\u00fchrung erf\u00fcllen ihren Zweck am besten, wenn sie als Teil eines umfassenden Governance-Rahmenwerks durchgef\u00fchrt werden. Die folgenden Mechanismen und Rahmenbedingungen sollten parallel zu Pr\u00fcfungen der Rechnungsf\u00fchrung bestehen, um f\u00fcr Rechenschaftspflicht zu sorgen:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Systeme der \u00f6ffentlichen Finanzverwaltung (PFM): <\/strong>Die Systeme der \u00f6ffentlichen Finanzverwaltung (Public Financial Management System; PFM), kurz PFM-Systeme, umfassen Budgetplanung, -ausf\u00fchrung, Buchhaltung und Berichterstattung. Echtzeitdaten zu Staatsausgaben aus einem integrierten PFM-System erm\u00f6glichen effizientere und genauere Pr\u00fcfungen.<\/li>\n\n\n\n<li><strong>Legislative Aufsicht: <\/strong>Die Befugnis zur Durchsicht der Pr\u00fcfungsberichte sowie die Befugnis, Beamtinnen und Beamte vorzuladen sowie Korrekturma\u00dfnahmen durchzusetzen, sollten den Parlamenten und Pr\u00fcfungsaussch\u00fcssen \u00fcbertragen werden. Solche Ma\u00dfnahmen sorgen f\u00fcr mehr Rechenschaftspflicht und reduzieren gleichzeitig F\u00e4lle von Fehlverhalten.<\/li>\n\n\n\n<li><strong>Transparenzportale: <\/strong>Die Echtzeit-Abbildung von Staatsausgaben auf digitalen Plattformen st\u00e4rkt sowohl die Kontrolle als auch das Vertrauen seitens der \u00d6ffentlichkeit. Die Daten erm\u00f6glichen es B\u00fcrgerinnen und B\u00fcrgern sowie Kontrollorganisationen und den Medien, die Rechenschaftspflicht der Regierung aufrechtzuerhalten.<\/li>\n\n\n\n<li><strong>Whistleblower-Schutz: <\/strong>Interne Mechanismen, die es Insiderinnen und Insidern erm\u00f6glichen, finanzielle Unregelm\u00e4\u00dfigkeiten anonym zu melden, spielen eine entscheidende Rolle. Whistleblowerinnen und Whistleblower liefern oft den ersten Ansto\u00df f\u00fcr die Aufdeckung von Fehlverhalten, und Mechanismen zu ihrem Schutz steigern die Melderaten.<\/li>\n\n\n\n<li><strong>Beteiligung der Zivilgesellschaft: <\/strong>Nationale Organisationen, Interessenverb\u00e4nde und die Wissenschaft spielen eine entscheidende Rolle f\u00fcr die Interpretation von Pr\u00fcfungserkenntnissen, die Aufkl\u00e4rung der \u00d6ffentlichkeit und die F\u00f6rderung von Reformen.<\/li>\n\n\n\n<li><strong>Umsetzung und IT-gest\u00fctzte Monitoringmechanismen: <\/strong>Digitale Tools und Systeme bieten eine effektive Methode, um Governance-Rahmenwerke umzusetzen. Diese Tools und Systeme erm\u00f6glichen eine genaue Nachverfolgung von Reformen durch Fehlerreduktion sowie Datenkonsistenz und bieten gleichzeitig M\u00f6glichkeiten zur \u00dcberwachung in Echtzeit. Die Kombination von PFM-Systemen mit Transparenzportalen sowie Pr\u00fcfungsverfahren sorgt f\u00fcr mehr Rechenschaftspflicht und unterst\u00fctzt gleichzeitig die kontinuierliche Verbesserung.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Fallstudien: Wirkung effektiver Verfahren im Rahmen von Pr\u00fcfungen der Rechnungsf\u00fchrung<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Saudi-Arabien: der digitale Wandel der Obersten Rechnungskontrollbeh\u00f6rde<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Dr. Hussam Alangari, Pr\u00e4sident der Obersten Rechnungskontrollbeh\u00f6rde Saudi-Arabien (General Court of Audit; GCA), leitete den GCA durch einen grundlegenden Wandel, um dessen Pr\u00fcfungsleistung zu st\u00e4rken. Der GCA f\u00fchrte die elektronische Pr\u00fcfungsplattform \u201eShamel\u201c ein, die auf k\u00fcnstlicher Intelligenz (KI) basierende Pr\u00fcfungsmethoden mit Datenanalyse-Tools verband. Dieser digitale Wandel erm\u00f6glichte Datenzugriff in Echtzeit, verbesserte die Kommunikation zwischen dem GCA und den \u00fcberpr\u00fcften Stellen und st\u00e4rkte die Finanzaufsicht, um die Ziele der saudi-arabischen \u201eVision&nbsp;2030\u201c zu erreichen.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Kuwait: St\u00e4rkung der Unabh\u00e4ngigkeit des Pr\u00fcfungspersonals durch IT-Governance<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Eine Studie aus dem Jahr&nbsp;2023 untersuchte, wie kuwaitische islamische Banken die Unabh\u00e4ngigkeit externer Pr\u00fcferinnen und Pr\u00fcfer verbessern, und zwar durch die Umsetzung solider Rahmenwerke f\u00fcr IT-Governance. Die Banken legten klare IT-Richtlinien fest und stellten die Unterst\u00fctzung der Abteilungen sowie standardisierte Kennzahlen sicher, um ein Umfeld zu schaffen, das objektive und unabh\u00e4ngige Pr\u00fcfungspraktiken f\u00f6rdert. Die Studie ergab, dass Ma\u00dfnahmen zur IT-Governance einen wesentlichen Faktor darstellen, der es Pr\u00fcferinnen und Pr\u00fcfern erm\u00f6glicht, unabh\u00e4ngig zu arbeiten, was zu qualitativ hochwertigeren und zuverl\u00e4ssigeren Pr\u00fcfungen der Rechnungsf\u00fchrung im kuwaitischen Bankensektor f\u00fchrt.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Katar: KI-gest\u00fctzte Aufsicht in der Aufsichtsbeh\u00f6rde Qatar Financial Centre<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Die Aufsichtsbeh\u00f6rde Qatar Financial Centre band k\u00fcnstliche Intelligenz in ihre (Finanz-)Aufsichtst\u00e4tigkeiten ein. Die Beh\u00f6rde setzte KI-gest\u00fctzte Entscheidungshilfen ein, um die \u00dcberwachung von Finanzinstituten zu verbessern, Pr\u00fcfungen der Einhaltung von Vorschriften zu beschleunigen sowie die Genauigkeit von Risikobeurteilungen zu erh\u00f6hen. Diese Ver\u00e4nderung steht im Einklang mit Katars Strategien in Richtung datengest\u00fctzter Regierungsf\u00fchrung, finanzieller Integrit\u00e4t und dem Einsatz von Technologie in der proaktiven Pr\u00fcfungsaufsicht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Herausforderungen und Chancen<\/h2>\n\n\n\n<p>Pr\u00fcfungen der Rechnungsf\u00fchrung sto\u00dfen trotz ihrer zahlreichen Vorteile auf vielf\u00e4ltige Hindernisse, darunter die folgenden:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rechnungskontrollbeh\u00f6rden in Entwicklungsl\u00e4ndern mangelt es an geschultem Personal und geeigneten Hilfsmitteln.<\/li>\n\n\n\n<li>Politische Einflussnahme und fehlende Unabh\u00e4ngigkeit untergraben die Glaubw\u00fcrdigkeit und Wirksamkeit der Pr\u00fcfungen.<\/li>\n\n\n\n<li>Wenn keine angemessenen Follow-up-Mechanismen vorhanden sind, f\u00fchrt dies zu einer schwachen Durchsetzung der Pr\u00fcfungsempfehlungen.<\/li>\n\n\n\n<li>Die Beteiligung der \u00d6ffentlichkeit ist in bestimmten Gebieten eingeschr\u00e4nkt, da die Menschen keine Kenntnis von Pr\u00fcfberichten haben und nicht wissen, wie sie diese nutzen k\u00f6nnen, um Rechenschaftspflicht durchzusetzen.<\/li>\n<\/ul>\n\n\n\n<p>Oberste Rechnungskontrollbeh\u00f6rden (ORKB) sind immer wieder mit diesen Hindernissen, die ihre operative Wirksamkeit beeintr\u00e4chtigen, konfrontiert. Die am h\u00e4ufigsten auftretenden Probleme sind in Abbildung&nbsp;2 dargestellt. Dazu z\u00e4hlen Personalmangel, politische Einflussnahme und mangelhafte Follow-up-Systeme.<\/p>\n\n\n\n<p>Es gibt mehrere L\u00f6sungen, um diese Herausforderungen in Angriff zu nehmen, darunter:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Einsatz fortschrittlicher Tools, die KI und Datenanalyse nutzen, um die Bereiche Pr\u00fcfungsplanung, Risikoerkennung und Betrugsanalyse zu verbessern.<\/li>\n\n\n\n<li>Internationale Zusammenarbeit mit Rechnungskontrollbeh\u00f6rden und Geberorganisationen, was den Ausbau von institutionellen Sachkompetenzen erm\u00f6glicht.<\/li>\n\n\n\n<li>Leistungssteigerungen durch Peer-Bewertungen und Benchmarking-Verfahren.<\/li>\n\n\n\n<li>Einsatz von Technologie und modernen mobilen Anwendungen, um eine Finanzaufsicht in Echtzeit zu erm\u00f6glichen.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"994\" height=\"660\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.002.jpeg\" alt=\"\" class=\"wp-image-41723\" srcset=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.002.jpeg 994w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.002-300x199.jpeg 300w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.002-768x510.jpeg 768w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.002-193x128.jpeg 193w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.002-310x206.jpeg 310w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.002-467x310.jpeg 467w, https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/7_GRAPHICS_Featurearticle_Kuwait_DE.002-426x282.jpeg 426w\" sizes=\"auto, (max-width: 994px) 100vw, 994px\" \/><figcaption class=\"wp-element-caption\">Abbildung\u00a02: H\u00e4ufigste Herausforderungen f\u00fcr Oberste Rechnungskontrollbeh\u00f6rden (INTOSAI Entwicklungsinitiative, 2020)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Fazit<\/h2>\n\n\n\n<p>Pr\u00fcfungen der Rechnungsf\u00fchrung, die sich an bew\u00e4hrte Verfahren halten und transparent durchgef\u00fchrt werden, leisten einen wesentlichen Beitrag zur F\u00f6rderung einer guten Verwaltung \u00f6ffentlicher Gelder. Solche Pr\u00fcfungsverfahren erm\u00f6glichen es Institutionen, ihre Ressourcen zu sch\u00fctzen, decken Ineffizienzen auf und verhindern Korruption. Die Einbindung der \u00d6ffentlichkeit, gekoppelt mit moderner Technologie und soliden Aufsichtsrahmen, macht diese Pr\u00fcfungen zu wirksameren Triebkr\u00e4ften der Rechenschaftspflicht.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Quellenangaben<\/strong><\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>ISSAI\u00a0100: Allgemeine Grunds\u00e4tze der staatlichen Finanzkontrolle <a href=\"https:\/\/www.issai.org\/pronouncements\/issai-100-fundamental-principles-of-public-sector-auditing\/\">https:\/\/www.issai.org\/pronouncements\/issai-100-fundamental-principles-of-public-sector-auditing\/<\/a><\/li>\n\n\n\n<li>ISSAI\u00a0200: Grunds\u00e4tze der Pr\u00fcfung der Rechnungsf\u00fchrung. <a href=\"https:\/\/www.issai.org\/pronouncements\/financial-audit-principles\/\">https:\/\/www.issai.org\/pronouncements\/financial-audit-principles\/<\/a><\/li>\n\n\n\n<li>ISSAI\u00a0300: Grunds\u00e4tze der Wirtschaftlichkeitspr\u00fcfung. <a href=\"https:\/\/www.issai.org\/pronouncements\/issai-300-performance-audit-principles\/\">https:\/\/www.issai.org\/pronouncements\/issai-300-performance-audit-principles\/<\/a><\/li>\n\n\n\n<li>ISSAI\u00a0400: Grunds\u00e4tze der Recht- und Ordnungsm\u00e4\u00dfigkeitspr\u00fcfung. <a href=\"https:\/\/www.issai.org\/pronouncements\/issai-400-compliance-audit-principles\/\">https:\/\/www.issai.org\/pronouncements\/issai-400-compliance-audit-principles\/<\/a><\/li>\n\n\n\n<li>Offizielle INTOSAI-Website: <a href=\"https:\/\/www.intosai.org\/\">https:\/\/www.intosai.org\/<\/a><\/li>\n\n\n\n<li>OECD Public Integrity Handbook. <a href=\"https:\/\/www.oecd.org\/en\/publications\/oecd-public-integrity-handbook_ac8ed8e8-en.html\">https:\/\/www.oecd.org\/en\/publications\/oecd-public-integrity-handbook_ac8ed8e8-en.html<\/a><\/li>\n\n\n\n<li>OECD Public Integrity Indicators. <a href=\"https:\/\/oecd-public-integrity-indicators.org\/\">https:\/\/oecd-public-integrity-indicators.org\/<\/a><\/li>\n\n\n\n<li>OECD (2024). Survey on the Drivers of Trust in Public Institutions. <a href=\"https:\/\/www.oecd.org\/gov\/trust-in-government.html\">https:\/\/www.oecd.org\/gov\/trust-in-government.html<\/a><\/li>\n\n\n\n<li>INTOSAI Entwicklungsinitiative (2020). Global SAI Stocktaking Report. <a href=\"https:\/\/gsr.idi.no\/gsr2020\">https:\/\/gsr.idi.no\/gsr2020<\/a><\/li>\n\n\n\n<li>Wikipedia (2025). Hussam bin Abdulmohsen Alangari. <a href=\"https:\/\/en.wikipedia.org\/wiki\/Hussam_bin_Abdulmohsen_Alangari\">https:\/\/en.wikipedia.org\/wiki\/Hussam_bin_Abdulmohsen_Alangari<\/a><\/li>\n\n\n\n<li>Hossain, I. (2024). Transition to AI-Augmented Decision-Making in Financial Supervision: Case Study in Qatar Financial Centre Regulatory Authority. <a href=\"https:\/\/aaltodoc.aalto.fi\/items\/1ab74b73-c3b1-41c0-8249-e5f3a2e8f056\">https:\/\/aaltodoc.aalto.fi\/items\/1ab74b73-c3b1-41c0-8249-e5f3a2e8f056<\/a><\/li>\n\n\n\n<li>The Impact of Applying Information Technology Governance in Kuwaiti Banks to Realize the Independence of the External Auditor.<a href=\"https:\/\/www.researchgate.net\/publication\/376666203_The_Impact_Of_Applying_Information_Technology_Governance_In_Kuwaiti_Banks_To_Realize_The_Independence_Of_The_External_Auditor\"> https:\/\/www.researchgate.net\/publication\/376666203_The_Impact_Of_Applying_Information_Technology_Governance_In_Kuwaiti_Banks_To_Realize_The_Independence_Of_The_External_Auditor<\/a><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr eine gute Regierungsf\u00fchrung m\u00fcssen \u00f6ffentliche Gelder transparent und effizient verwaltet werden. Pr\u00fcfungen der Rechnungsf\u00fchrung und Aufsichtsmechanismen haben zunehmend an Bedeutung gewonnen, da das Vertrauen der \u00d6ffentlichkeit eng mit finanzieller Rechenschaftspflicht verkn\u00fcpft ist. Diese Pr\u00fcfungen und Mechanismen verfolgen zwei Hauptziele: die Aufdeckung sowie Verhinderung von Korruption und Misswirtschaft sowie die F\u00f6rderung von Transparenz und die St\u00e4rkung von Institutionen, um B\u00fcrgerinnen und B\u00fcrgern greifbare Nutzen zu verschaffen.<\/p>\n","protected":false},"author":441,"featured_media":41681,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[4502],"content-tags":[2153,2143,2229,2174],"country":[4021],"region":[2592],"section":[2603],"coauthors":[4507],"class_list":["post-41716","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-q2-2026","content-tags-beaufsichtigung","content-tags-gute-regierungsfuhrung","content-tags-rechenschaftspflicht","content-tags-transparenz","country-kuwait-de","region-arabosai-de-2","section-fachartikel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00fcfungen der Rechnungsf\u00fchrung und Mechanismen f\u00fcr eine gute Verwaltung \u00f6ffentlicher Mittel: F\u00f6rderung von Rechenschaftspflicht, Transparenz und b\u00fcrgerlichem Vertrauen durch Aufsicht sowie bew\u00e4hrte Verfahren - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00fcfungen der Rechnungsf\u00fchrung und Mechanismen f\u00fcr eine gute Verwaltung \u00f6ffentlicher Mittel: F\u00f6rderung von Rechenschaftspflicht, Transparenz und b\u00fcrgerlichem Vertrauen durch Aufsicht sowie bew\u00e4hrte Verfahren - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"F\u00fcr eine gute Regierungsf\u00fchrung m\u00fcssen \u00f6ffentliche Gelder transparent und effizient verwaltet werden. Pr\u00fcfungen der Rechnungsf\u00fchrung und Aufsichtsmechanismen haben zunehmend an Bedeutung gewonnen, da das Vertrauen der \u00d6ffentlichkeit eng mit finanzieller Rechenschaftspflicht verkn\u00fcpft ist. Diese Pr\u00fcfungen und Mechanismen verfolgen zwei Hauptziele: die Aufdeckung sowie Verhinderung von Korruption und Misswirtschaft sowie die F\u00f6rderung von Transparenz und die St\u00e4rkung von Institutionen, um B\u00fcrgerinnen und B\u00fcrgern greifbare Nutzen zu verschaffen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T19:28:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/AdobeStock_201973585-Large.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"May Al-Roomi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/\",\"url\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/\",\"name\":\"Pr\u00fcfungen der Rechnungsf\u00fchrung und Mechanismen f\u00fcr eine gute Verwaltung \u00f6ffentlicher Mittel: F\u00f6rderung von Rechenschaftspflicht, Transparenz und b\u00fcrgerlichem Vertrauen durch Aufsicht sowie bew\u00e4hrte Verfahren - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/AdobeStock_201973585-Large.jpeg\",\"datePublished\":\"2026-06-30T16:15:00+00:00\",\"dateModified\":\"2026-07-14T19:28:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/#primaryimage\",\"url\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/AdobeStock_201973585-Large.jpeg\",\"contentUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/AdobeStock_201973585-Large.jpeg\",\"width\":1280,\"height\":853,\"caption\":\"Quelle: Adobe Stock Images, Jirapong\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00fcfungen der Rechnungsf\u00fchrung und Mechanismen f\u00fcr eine gute Verwaltung \u00f6ffentlicher Mittel: F\u00f6rderung von Rechenschaftspflicht, Transparenz und b\u00fcrgerlichem Vertrauen durch Aufsicht sowie bew\u00e4hrte Verfahren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#website\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intosaijournal.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00fcfungen der Rechnungsf\u00fchrung und Mechanismen f\u00fcr eine gute Verwaltung \u00f6ffentlicher Mittel: F\u00f6rderung von Rechenschaftspflicht, Transparenz und b\u00fcrgerlichem Vertrauen durch Aufsicht sowie bew\u00e4hrte Verfahren - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/","og_locale":"de_DE","og_type":"article","og_title":"Pr\u00fcfungen der Rechnungsf\u00fchrung und Mechanismen f\u00fcr eine gute Verwaltung \u00f6ffentlicher Mittel: F\u00f6rderung von Rechenschaftspflicht, Transparenz und b\u00fcrgerlichem Vertrauen durch Aufsicht sowie bew\u00e4hrte Verfahren - INTOSAI Journal","og_description":"F\u00fcr eine gute Regierungsf\u00fchrung m\u00fcssen \u00f6ffentliche Gelder transparent und effizient verwaltet werden. Pr\u00fcfungen der Rechnungsf\u00fchrung und Aufsichtsmechanismen haben zunehmend an Bedeutung gewonnen, da das Vertrauen der \u00d6ffentlichkeit eng mit finanzieller Rechenschaftspflicht verkn\u00fcpft ist. Diese Pr\u00fcfungen und Mechanismen verfolgen zwei Hauptziele: die Aufdeckung sowie Verhinderung von Korruption und Misswirtschaft sowie die F\u00f6rderung von Transparenz und die St\u00e4rkung von Institutionen, um B\u00fcrgerinnen und B\u00fcrgern greifbare Nutzen zu verschaffen.","og_url":"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/","og_site_name":"INTOSAI Journal","article_modified_time":"2026-07-14T19:28:03+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/AdobeStock_201973585-Large.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"1 minute","Written by":"May Al-Roomi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/","url":"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/","name":"Pr\u00fcfungen der Rechnungsf\u00fchrung und Mechanismen f\u00fcr eine gute Verwaltung \u00f6ffentlicher Mittel: F\u00f6rderung von Rechenschaftspflicht, Transparenz und b\u00fcrgerlichem Vertrauen durch Aufsicht sowie bew\u00e4hrte Verfahren - INTOSAI Journal","isPartOf":{"@id":"https:\/\/www.intosaijournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/#primaryimage"},"image":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/#primaryimage"},"thumbnailUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/AdobeStock_201973585-Large.jpeg","datePublished":"2026-06-30T16:15:00+00:00","dateModified":"2026-07-14T19:28:03+00:00","breadcrumb":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/#primaryimage","url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/AdobeStock_201973585-Large.jpeg","contentUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/AdobeStock_201973585-Large.jpeg","width":1280,"height":853,"caption":"Quelle: Adobe Stock Images, Jirapong"},{"@type":"BreadcrumbList","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/pruefungen-der-rechnungsfuehrung-und-mechanismen-fuer-eine-gute-verwaltung-oeffentlicher-mittel-foerderung-von-rechenschaftspflicht-transparenz-und-buergerlichem-vertrauen-durch-aufsicht-sowie-bewae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/de\/"},{"@type":"ListItem","position":2,"name":"Pr\u00fcfungen der Rechnungsf\u00fchrung und Mechanismen f\u00fcr eine gute Verwaltung \u00f6ffentlicher Mittel: F\u00f6rderung von Rechenschaftspflicht, Transparenz und b\u00fcrgerlichem Vertrauen durch Aufsicht sowie bew\u00e4hrte Verfahren"}]},{"@type":"WebSite","@id":"https:\/\/www.intosaijournal.org\/es\/#website","url":"https:\/\/www.intosaijournal.org\/es\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/www.intosaijournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intosaijournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.intosaijournal.org\/es\/#organization","name":"INTOSAI Journal","url":"https:\/\/www.intosaijournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/41716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/users\/441"}],"version-history":[{"count":1,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/41716\/revisions"}],"predecessor-version":[{"id":41728,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/41716\/revisions\/41728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/media\/41681"}],"wp:attachment":[{"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/media?parent=41716"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-categories?post=41716"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/content-tags?post=41716"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/country?post=41716"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/region?post=41716"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/section?post=41716"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/coauthors?post=41716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}