{"id":14329,"date":"2022-01-26T16:44:34","date_gmt":"2022-01-26T21:44:34","guid":{"rendered":"https:\/\/intosai.nclud.com\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/"},"modified":"2023-05-04T02:41:12","modified_gmt":"2023-05-04T06:41:12","slug":"global-stocktaking-shows-slow-progress-in-difficult-waters","status":"publish","type":"journal-entry","link":"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/","title":{"rendered":"Globale Bestandsaufnahme zeigt langsame Fortschritte in schwierigem Fahrwasser"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"http:\/\/intosaijournal.org\/wp-content\/uploads\/2022\/01\/GSR-2020-cover-image.jpg\" alt=\"\" class=\"wp-image-23709\"\/><\/figure>\n\n\n\n<p><em>von Camilla Fredriksen, Managerin, IDI Global Foundations Unit  <\/em><\/p>\n\n\n\n<p>Im September 2021 ver\u00f6ffentlichte die INTOSAI-Entwicklungsinitiative (IDI) den <a href=\"https:\/\/www.idi.no\/news\/gsr2020-report\">Globalen Bericht \u00fcber die Bestandsaufnahme der Obersten Rechnungskontrollbeh\u00f6rden (ORKB) 2020<\/a>, die vierte dreij\u00e4hrliche Analyse der Daten aus einer globalen Umfrage der INTOSAI \u00fcber die Leistung und die Kapazit\u00e4ten der ORKB. Der Bericht, der den Zeitraum von 2017 bis 2019 abdeckt, markiert das zehnj\u00e4hrige Jubil\u00e4um der Globalen Bestandsaufnahme, die f\u00fcr die INTOSAI und die Geber eine wichtige Informationsquelle \u00fcber die Bed\u00fcrfnisse der ORKB war.<\/p>\n\n\n\n<p>Viele ORKB arbeiten in einem schwierigen Umfeld, in dem die Mechanismen der Rechenschaftspflicht unter Druck stehen. Trotz dieser Herausforderungen zeichnet die diesj\u00e4hrige Globale Bestandsaufnahme, an der 178 ORKB teilnahmen, das Bild einer ORKB-Gemeinschaft, in der sich Leistung und Kapazit\u00e4ten langsam verbessern. Dieser Artikel fasst einige der wichtigsten Aussagen des Berichts zusammen.<\/p>\n\n\n\n<p><strong>ISSAI-konforme Praktiken erfordern Ressourcen und robuste Qualit\u00e4tssysteme  <\/strong><br>Vor dem Hintergrund des demokratischen R\u00fcckschritts und der zunehmenden Korruption bem\u00fchen sich die ORKB um die Annahme der internationalen Normen f\u00fcr ORKB (ISSAIs). Diese Bem\u00fchungen scheinen zu einem besseren Verst\u00e4ndnis dessen zu f\u00fchren, was die Umsetzung der ISSAIs wirklich bedeutet, einschlie\u00dflich dessen, was die Unabh\u00e4ngigkeit der ORKB in der Praxis bedeuten sollte.<\/p>\n\n\n\n<p>Die \u00dcbernahme von ISSAIs hat seit 2017 zugenommen. 86 Prozent der ORKB berichten, dass sie ISSAIs f\u00fcr ihre wichtigsten Pr\u00fcfungsbereiche umgesetzt haben. Fast die H\u00e4lfte der Befragten hat die Normen direkt \u00fcbernommen, w\u00e4hrend die andere H\u00e4lfte nationale Normen \u00fcbernommen hat, die auf den ISSAIs basieren oder mit ihnen \u00fcbereinstimmen.<\/p>\n\n\n\n<p>Um den Kontext dieser Reaktionen vollst\u00e4ndig zu verstehen, sind weitere Untersuchungen erforderlich. ORKB, die ISSAIs direkt \u00fcbernehmen, tun dies m\u00f6glicherweise, weil es in ihrem Land keine nationalen Pr\u00fcfungsnormen gibt. Bei der anderen H\u00e4lfte ist das Ausma\u00df, in dem die nationalen Normen mit allen Elementen der ISSAI \u00fcbereinstimmen, wahrscheinlich unterschiedlich.<\/p>\n\n\n\n<p>Die Verabschiedung von Normen ist jedoch nur der erste Schritt, und die globale Bestandsaufnahme zeigt, dass viele ORKB noch weit von einer ISSAI-konformen Pr\u00fcfungspraxis entfernt sind. Zwar gaben 68 Prozent der ORKB an, dass sie die ISSAIs weitgehend einhalten, doch eine Analyse einer Stichprobe von 42 Bewertungen des <a href=\"https:\/\/www.idi.no\/work-streams\/well-governed-sais\/sai-pmf\">Rahmens f\u00fcr Leistungsmessung (Performance Measurement Framework, PMF<\/a> ) deutet darauf hin, dass sich dies nur auf die Qualit\u00e4t der Pr\u00fcfungshandb\u00fccher, nicht aber auf die Pr\u00fcfungspraxis bezog.<\/p>\n\n\n\n<p>In der globalen Umfrage gaben 44 Prozent der ORKB an, dass der Hauptgrund f\u00fcr die Nichteinhaltung der ISSAIs fehlende Ressourcen und begrenzte Kapazit\u00e4ten sind. Ein weiterer Faktor war das Fehlen eines angemessenen Qualit\u00e4tsmanagementsystems, das die Pr\u00fcfungsprozesse lenken und Qualit\u00e4tsm\u00e4ngel systematisch angehen w\u00fcrde. Ein Viertel der ORKB verf\u00fcgte \u00fcber keines der Merkmale, die ein solides Qualit\u00e4tsmanagementsystem ausmachen. In Anbetracht dieser Herausforderungen ist es ermutigend, dass fast alle ORKB den Ausbau ihrer Kapazit\u00e4ten in Schl\u00fcsselbereichen wie Pr\u00fcfungsplanung, -durchf\u00fchrung und -berichterstattung planten.<\/p>\n\n\n\n<p><strong>Die Bedrohung der Unabh\u00e4ngigkeit der ORKB bleibt eine Herausforderung  <\/strong><br>Der Bericht zeigt deutlich, dass die Bedrohung der Unabh\u00e4ngigkeit der ORKB nach wie vor eine ernsthafte Herausforderung darstellt, da die Ergebnisse f\u00fcr sieben der acht Grunds\u00e4tze der <a href=\"https:\/\/www.issai.org\/pronouncements\/intosai-p-10-mexico-declaration-on-sai-independence\/\">Deklaration von Mexiko<\/a> r\u00fcckl\u00e4ufig sind. Unerw\u00fcnschte Eingriffe von au\u00dfen schr\u00e4nkten die F\u00e4higkeit der ORKB ein, ihr Mandat zu erf\u00fcllen, was ernsthafte Risiken f\u00fcr Transparenz und Rechenschaftspflicht mit sich brachte. Fast die H\u00e4lfte der ORKB bekundete ihr Interesse an einer St\u00e4rkung ihres rechtlichen Rahmens und ihrer Unabh\u00e4ngigkeit.<\/p>\n\n\n\n<p>Wie fr\u00fchere Global Surveys gezeigt haben, sind finanzielle und operative Autonomie nach wie vor die gr\u00f6\u00dften Herausforderungen f\u00fcr die Unabh\u00e4ngigkeit. Vierzig Prozent der ORKB berichteten, dass sie erhebliche St\u00f6rungen im Haushaltsvollzug erlebt haben. W\u00e4hrend die meisten ORKB \u00fcber ein gewisses Ma\u00df an Autonomie im Tagesgesch\u00e4ft berichteten, kontrollierten nur 63 Prozent die Einstellung von Personal vollst\u00e4ndig, und rund 70 Prozent gaben an, dass ihr Personal entweder zahlenm\u00e4\u00dfig oder fachlich unzureichend sei.<\/p>\n\n\n\n<p>Die ORKB erlebten auch eine direkte Einmischung der Exekutive in ihre Pr\u00fcfungst\u00e4tigkeit. Das \u00fcberraschendste Ergebnis war, dass nur 44 Prozent der ORKB \u00fcber einen vollst\u00e4ndigen und rechtzeitigen  Zugang zu Informationen f\u00fcr ihre Pr\u00fcfungen verf\u00fcgten, was einem R\u00fcckgang von 26 Prozent gegen\u00fcber 2017 entspricht.<\/p>\n\n\n\n<p>Die Daten deuten auch darauf hin, dass die Auswahl der Pr\u00fcfungsprogramme &#8211; ein Bereich, in dem die meisten ORKB mehr Freiheit erfahren haben &#8211; mit dem Grad der Demokratie zusammenh\u00e4ngt. ORKB in L\u00e4ndern mit weniger demokratischem Raum erlebten mehr Einmischung bei der Entscheidung \u00fcber ihre j\u00e4hrlichen Pr\u00fcfungsprogramme. Auch die Berichterstattung \u00fcber die Ergebnisse stellte eine Herausforderung dar: 12 Prozent der Befragten ver\u00f6ffentlichten \u00fcberhaupt keine Berichte.<\/p>\n\n\n\n<p><strong>Gr\u00f6\u00dfere Transparenz und strategischere Kommunikation sind erforderlich<\/strong><br>W\u00e4hrend die St\u00e4rkung der Unabh\u00e4ngigkeit der ORKB f\u00fcr die \u00dcberwachung der \u00f6ffentlichen Ausgaben von entscheidender Bedeutung ist, schl\u00e4gt der Bericht weitere wichtige Schritte vor, die die ORKB unternehmen k\u00f6nnen, um Transparenz und Rechenschaftspflicht zu f\u00f6rdern und ihre Wirkung zu verst\u00e4rken.<\/p>\n\n\n\n<p>Der Bericht zeigt, dass die ORKB ihre eigene T\u00e4tigkeit transparenter gestalten k\u00f6nnten. W\u00e4hrend fast alle ORKB \u00fcber strategische Pl\u00e4ne verf\u00fcgten, berichteten nur 57 Prozent \u00f6ffentlich dar\u00fcber, inwieweit sie ihre Ziele erreicht haben. Von den 72 Prozent der ORKB, die Jahresabschl\u00fcsse erstellten, unterzogen nur 73 Prozent diese einer externen Pr\u00fcfung, und noch weniger berichteten \u00f6ffentlich \u00fcber die Pr\u00fcfungsergebnisse. Ebenso hatten zwar viele ORKB PMF-Bewertungen durchgef\u00fchrt, aber nur sehr wenige hatten ihre St\u00e4rken und Herausforderungen \u00f6ffentlich gemacht.<\/p>\n\n\n\n<p>Ein wichtiger Indikator f\u00fcr die Wirkung der ORKB ist das Ausma\u00df, in dem die gepr\u00fcften Stellen ihre Empfehlungen umsetzen. Die ORKB berichteten, dass von 2017 bis 2019 nur die H\u00e4lfte ihrer Empfehlungen umgesetzt wurden. Die globale Bestandsaufnahme zeigt einen starken R\u00fcckgang des Prozentsatzes der ORKB, die \u00fcber ein internes System zur Weiterverfolgung von Empfehlungen verf\u00fcgen, was zu einer geringeren Pr\u00fcfungswirkung beigetragen haben k\u00f6nnte.<\/p>\n\n\n\n<p>Die ORKB berichteten, dass fehlende Reaktionen der Exekutive und fehlende Folgema\u00dfnahmen der Legislative die gr\u00f6\u00dften Hindernisse bei der Erzielung von Pr\u00fcfungsergebnissen darstellen, was durch die Daten <a href=\"https:\/\/www.internationalbudget.org\/open-budget-survey\/rankings\">des Open Budget Index<\/a> best\u00e4tigt wird. Allerdings gaben weniger als die H\u00e4lfte der ORKB an, dass sie die Exekutive und Legislative bei der Weiterverfolgung der Umsetzung von Pr\u00fcfungsempfehlungen einbeziehen. Viele ORKB kommunizierten regelm\u00e4\u00dfig mit diesen Interessengruppen, aber ihre Art und Weise, dies zu tun, war nicht immer strategisch.<\/p>\n\n\n\n<p>W\u00e4hrend die ORKBn auf Allianzen achten sollten, die die Wahrnehmung ihrer Objektivit\u00e4t beeintr\u00e4chtigen k\u00f6nnten, k\u00f6nnten sie die Interessengruppen der Exekutive und Legislative st\u00e4rker einbeziehen, um den Regierungen zu helfen, besser zu verstehen, wie sie die Pr\u00fcfungsergebnisse nutzen k\u00f6nnen. Dar\u00fcber hinaus sind einige Fragen eher systemischer Natur und m\u00fcssen daher auf einer h\u00f6heren Ebene als nur den untersuchten Unternehmen mitgeteilt werden. Die Ergebnisse der Umfrage best\u00e4tigen erneut, wie wichtig es ist, Pr\u00fcfungen ganzheitlich anzugehen und sich auf die strategische Kommunikation mit den wichtigsten Interessengruppen zu konzentrieren.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"http:\/\/intosaijournal.org\/wp-content\/uploads\/2022\/01\/INTOSAI-Journal_Winter-2022_GSR_graph-adjusted_web.jpg\" alt=\"\" class=\"wp-image-23948\"\/><\/figure>\n\n\n\n<p><strong>INTOSAI-Gremien und ORKB leisten entscheidende Unterst\u00fctzung<\/strong><br>Der Bericht best\u00e4tigt die wichtige Rolle der regionalen INTOSAI-Gremien als Anbieter von Leitlinien, Instrumenten und Unterst\u00fctzung f\u00fcr ORKB an vorderster Front. Die Umfrageergebnisse deuten darauf hin, dass diese Organisationen &#8211; mit ihrem einzigartigen Verst\u00e4ndnis des regionalen Kontextes &#8211; auf die Bed\u00fcrfnisse der ORKB eingehen und ihre Initiativen unter Einbeziehung der Mitglieder entwickeln. Sie f\u00f6rderten am st\u00e4rksten die Pr\u00fcfungskapazit\u00e4ten, haben aber das Potenzial, den ORKB auch in anderen Bereichen mehr zu helfen. Dar\u00fcber hinaus ergab die globale Umfrage, dass die von anderen INTOSAI-Gremien, wie den Zielkomitees, entwickelten Normen, Leitlinien und Ressourcen weit verbreitet sind.<\/p>\n\n\n\n<p>Die Globale Erhebung bot auch die Gelegenheit, die Zusammenarbeit der INTOSAI-Mitglieder untereinander zu bewerten. Kooperative Audits waren weiterhin ein beliebtes Mittel zur Zusammenarbeit und zum Wissensaustausch. 75 Prozent der Befragten aus allen Regionen haben sich an diesen Bem\u00fchungen beteiligt.<\/p>\n\n\n\n<p>Einundsiebzig ORKB berichteten, dass sie anderen ORKB Peer-to-Peer-Unterst\u00fctzung geleistet haben, ein R\u00fcckgang gegen\u00fcber 87 im Jahr 2017; dieser R\u00fcckgang k\u00f6nnte auf den gemeldeten Bedarf an externer Finanzierung f\u00fcr diese Bem\u00fchungen zur\u00fcckzuf\u00fchren sein. Zwar erkl\u00e4rten sich 67 ORKB bereit, diese Initiativen in der kommenden Zeit zu leiten oder zu unterst\u00fctzen, doch kann die Nachfrage nach Peer-to-Peer-Unterst\u00fctzung ohne zus\u00e4tzliche Geberpartner nicht gedeckt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im September 2021 ver\u00f6ffentlichte die INTOSAI-Entwicklungsinitiative (IDI) den Globalen Bericht \u00fcber die Bestandsaufnahme der Obersten Rechnungskontrollbeh\u00f6rden (ORKB) 2020, die vierte dreij\u00e4hrliche Analyse der Daten aus einer globalen Umfrage der INTOSAI \u00fcber die Leistung und die Kapazit\u00e4ten der ORKB. Der Bericht, der den Zeitraum von 2017 bis 2019 abdeckt, markiert das 10-j\u00e4hrige Jubil\u00e4um der globalen Bestandsaufnahme, die eine wichtige Quelle f\u00fcr&#8230;<\/p>\n","protected":false},"author":60,"featured_media":7748,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[2509,2521,2566],"content-tags":[2136,2170,2139,2225,2174,2207,2145,2146],"country":[],"region":[],"section":[2662],"coauthors":[],"class_list":["post-14329","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-innerhalb-der-intosai","journal-categories-intosai-entwicklungsinitiative-de","journal-categories-winter-2022-de","content-tags-aufbau-von-kapazitaten","content-tags-idi-de","content-tags-internationale-normen","content-tags-kommunikation","content-tags-transparenz","content-tags-unabhangigkeit","content-tags-zusammenarbeit","content-tags-zusammenarbeit-de","section-innerhalb-der-intosai"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Globale Bestandsaufnahme zeigt langsame Fortschritte in schwierigem Fahrwasser - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Globale Bestandsaufnahme zeigt langsame Fortschritte in schwierigem Fahrwasser - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"Im September 2021 ver\u00f6ffentlichte die INTOSAI-Entwicklungsinitiative (IDI) den Globalen Bericht \u00fcber die Bestandsaufnahme der Obersten Rechnungskontrollbeh\u00f6rden (ORKB) 2020, die vierte dreij\u00e4hrliche Analyse der Daten aus einer globalen Umfrage der INTOSAI \u00fcber die Leistung und die Kapazit\u00e4ten der ORKB. Der Bericht, der den Zeitraum von 2017 bis 2019 abdeckt, markiert das 10-j\u00e4hrige Jubil\u00e4um der globalen Bestandsaufnahme, die eine wichtige Quelle f\u00fcr...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-04T06:41:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/02\/GSR-2020-cover-image_thumbnail_web-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Camilla Fredriksen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/\",\"url\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/\",\"name\":\"Globale Bestandsaufnahme zeigt langsame Fortschritte in schwierigem Fahrwasser - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/intosaijournal.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/02\/GSR-2020-cover-image_thumbnail_web-1.jpg\",\"datePublished\":\"2022-01-26T21:44:34+00:00\",\"dateModified\":\"2023-05-04T06:41:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/#primaryimage\",\"url\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/02\/GSR-2020-cover-image_thumbnail_web-1.jpg\",\"contentUrl\":\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/02\/GSR-2020-cover-image_thumbnail_web-1.jpg\",\"width\":724,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Globale Bestandsaufnahme zeigt langsame Fortschritte in schwierigem Fahrwasser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intosaijournal.org\/#website\",\"url\":\"https:\/\/intosaijournal.org\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intosaijournal.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intosaijournal.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intosaijournal.org\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/intosaijournal.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Globale Bestandsaufnahme zeigt langsame Fortschritte in schwierigem Fahrwasser - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/","og_locale":"de_DE","og_type":"article","og_title":"Globale Bestandsaufnahme zeigt langsame Fortschritte in schwierigem Fahrwasser - INTOSAI Journal","og_description":"Im September 2021 ver\u00f6ffentlichte die INTOSAI-Entwicklungsinitiative (IDI) den Globalen Bericht \u00fcber die Bestandsaufnahme der Obersten Rechnungskontrollbeh\u00f6rden (ORKB) 2020, die vierte dreij\u00e4hrliche Analyse der Daten aus einer globalen Umfrage der INTOSAI \u00fcber die Leistung und die Kapazit\u00e4ten der ORKB. Der Bericht, der den Zeitraum von 2017 bis 2019 abdeckt, markiert das 10-j\u00e4hrige Jubil\u00e4um der globalen Bestandsaufnahme, die eine wichtige Quelle f\u00fcr...","og_url":"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/","og_site_name":"INTOSAI Journal","article_modified_time":"2023-05-04T06:41:12+00:00","og_image":[{"width":724,"height":800,"url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/02\/GSR-2020-cover-image_thumbnail_web-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"6 minutes","Written by":"Camilla Fredriksen"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/","url":"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/","name":"Globale Bestandsaufnahme zeigt langsame Fortschritte in schwierigem Fahrwasser - INTOSAI Journal","isPartOf":{"@id":"https:\/\/intosaijournal.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/#primaryimage"},"image":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/#primaryimage"},"thumbnailUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/02\/GSR-2020-cover-image_thumbnail_web-1.jpg","datePublished":"2022-01-26T21:44:34+00:00","dateModified":"2023-05-04T06:41:12+00:00","breadcrumb":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/#primaryimage","url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/02\/GSR-2020-cover-image_thumbnail_web-1.jpg","contentUrl":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/02\/GSR-2020-cover-image_thumbnail_web-1.jpg","width":724,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/global-stocktaking-shows-slow-progress-in-difficult-waters\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/de\/"},{"@type":"ListItem","position":2,"name":"Globale Bestandsaufnahme zeigt langsame Fortschritte in schwierigem Fahrwasser"}]},{"@type":"WebSite","@id":"https:\/\/intosaijournal.org\/#website","url":"https:\/\/intosaijournal.org\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/intosaijournal.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intosaijournal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/intosaijournal.org\/#organization","name":"INTOSAI Journal","url":"https:\/\/intosaijournal.org\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/14329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/users\/60"}],"version-history":[{"count":3,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/14329\/revisions"}],"predecessor-version":[{"id":14341,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/14329\/revisions\/14341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/media\/7748"}],"wp:attachment":[{"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/media?parent=14329"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-categories?post=14329"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/content-tags?post=14329"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/country?post=14329"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/region?post=14329"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/section?post=14329"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/intosaijournal.org\/de\/wp-json\/wp\/v2\/coauthors?post=14329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}